{"id":375,"date":"2015-01-13T11:46:02","date_gmt":"2015-01-13T10:46:02","guid":{"rendered":"\/web\/?p=375"},"modified":"2015-02-19T12:29:36","modified_gmt":"2015-02-19T11:29:36","slug":"san-luigi-di-orbassano","status":"publish","type":"post","link":"\/web\/2015\/01\/13\/san-luigi-di-orbassano\/","title":{"rendered":"San Luigi di Orbassano: reparto TBC"},"content":{"rendered":"<p>Andrea Appiano interroga l&#8217;Assessore Saitta sul reparto Tubercolosi del San Luigi di Orbassano, spiegando che non deve essere smantellato e chiedendo tempi e modalit\u00e0 della riapertura. Antonio Saitta ha risposto confermando\u00a0che il reparto dell&#8217; Azienda Ospedaliera San Luigi di Orbassano non sar\u00e0 chiuso. I lavori inizieranno dopo la dismissione di tutti i pazienti e dureranno dai 3 ai 5-6 mesi!<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Andrea Appiano interroga l&#8217;Assessore Saitta sul reparto Tubercolosi del San Luigi di Orbassano, spiegando che non deve essere smantellato e chiedendo tempi e modalit\u00e0 della riapertura. Antonio Saitta ha risposto confermando\u00a0che il reparto dell&#8217; Azienda Ospedaliera San Luigi di Orbassano non sar\u00e0 chiuso. I lavori inizieranno dopo la dismissione di tutti i pazienti e dureranno [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":376,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[3,7],"tags":[38],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.12 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>San Luigi di Orbassano: reparto TBC - Partito Democratico<\/title>\n<meta name=\"description\" content=\"Andrea Appiano interroga l&#039;Assessore Saitta sul reparto tubercolosi del San Luigi di Orbassano\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"\/web\/2015\/01\/13\/san-luigi-di-orbassano\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"San Luigi di Orbassano: reparto TBC - Partito Democratico\" \/>\n<meta property=\"og:description\" content=\"Andrea Appiano interroga l&#039;Assessore Saitta sul reparto tubercolosi del San Luigi di Orbassano\" \/>\n<meta property=\"og:url\" content=\"\/web\/2015\/01\/13\/san-luigi-di-orbassano\/\" \/>\n<meta property=\"og:site_name\" content=\"Partito Democratico\" \/>\n<meta property=\"article:published_time\" content=\"2015-01-13T10:46:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-02-19T11:29:36+00:00\" \/>\n<meta property=\"og:image\" content=\"\/web\/wp-content\/uploads\/sites\/8\/2015\/02\/tubercolosi-orbassano.png\" \/>\n\t<meta property=\"og:image:width\" content=\"472\" \/>\n\t<meta property=\"og:image:height\" content=\"395\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"mastrodicasa\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"mastrodicasa\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"\/web\/2015\/01\/13\/san-luigi-di-orbassano\/\",\"url\":\"\/web\/2015\/01\/13\/san-luigi-di-orbassano\/\",\"name\":\"San Luigi di Orbassano: reparto TBC - Partito Democratico\",\"isPartOf\":{\"@id\":\"\/web\/#website\"},\"datePublished\":\"2015-01-13T10:46:02+00:00\",\"dateModified\":\"2015-02-19T11:29:36+00:00\",\"author\":{\"@id\":\"\/web\/#\/schema\/person\/e3213afc750e7648b3ad0561ab389690\"},\"description\":\"Andrea Appiano interroga l'Assessore Saitta sul reparto tubercolosi del San Luigi di Orbassano\",\"breadcrumb\":{\"@id\":\"\/web\/2015\/01\/13\/san-luigi-di-orbassano\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"\/web\/2015\/01\/13\/san-luigi-di-orbassano\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"\/web\/2015\/01\/13\/san-luigi-di-orbassano\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"San Luigi di Orbassano: reparto TBC\"}]},{\"@type\":\"WebSite\",\"@id\":\"\/web\/#website\",\"url\":\"\/web\/\",\"name\":\"Partito Democratico\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"\/web\/#\/schema\/person\/e3213afc750e7648b3ad0561ab389690\",\"name\":\"mastrodicasa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"\/web\/#\/schema\/person\/image\/\",\"url\":\"http:\/\/0.gravatar.com\/avatar\/3193e7cdcf94bcc77fa1c5b0cf49f5f6?s=96&d=mm&r=g\",\"contentUrl\":\"http:\/\/0.gravatar.com\/avatar\/3193e7cdcf94bcc77fa1c5b0cf49f5f6?s=96&d=mm&r=g\",\"caption\":\"mastrodicasa\"},\"url\":\"\/web\/author\/mastrodicasa\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"San Luigi di Orbassano: reparto TBC - Partito Democratico","description":"Andrea Appiano interroga l'Assessore Saitta sul reparto tubercolosi del San Luigi di Orbassano","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"\/web\/2015\/01\/13\/san-luigi-di-orbassano\/","og_locale":"it_IT","og_type":"article","og_title":"San Luigi di Orbassano: reparto TBC - Partito Democratico","og_description":"Andrea Appiano interroga l'Assessore Saitta sul reparto tubercolosi del San Luigi di Orbassano","og_url":"\/web\/2015\/01\/13\/san-luigi-di-orbassano\/","og_site_name":"Partito Democratico","article_published_time":"2015-01-13T10:46:02+00:00","article_modified_time":"2015-02-19T11:29:36+00:00","og_image":[{"width":472,"height":395,"url":"\/web\/wp-content\/uploads\/sites\/8\/2015\/02\/tubercolosi-orbassano.png","type":"image\/png"}],"author":"mastrodicasa","twitter_misc":{"Scritto da":"mastrodicasa"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"\/web\/2015\/01\/13\/san-luigi-di-orbassano\/","url":"\/web\/2015\/01\/13\/san-luigi-di-orbassano\/","name":"San Luigi di Orbassano: reparto TBC - Partito Democratico","isPartOf":{"@id":"\/web\/#website"},"datePublished":"2015-01-13T10:46:02+00:00","dateModified":"2015-02-19T11:29:36+00:00","author":{"@id":"\/web\/#\/schema\/person\/e3213afc750e7648b3ad0561ab389690"},"description":"Andrea Appiano interroga l'Assessore Saitta sul reparto tubercolosi del San Luigi di Orbassano","breadcrumb":{"@id":"\/web\/2015\/01\/13\/san-luigi-di-orbassano\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["\/web\/2015\/01\/13\/san-luigi-di-orbassano\/"]}]},{"@type":"BreadcrumbList","@id":"\/web\/2015\/01\/13\/san-luigi-di-orbassano\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"\/web\/"},{"@type":"ListItem","position":2,"name":"San Luigi di Orbassano: reparto TBC"}]},{"@type":"WebSite","@id":"\/web\/#website","url":"\/web\/","name":"Partito Democratico","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"\/web\/#\/schema\/person\/e3213afc750e7648b3ad0561ab389690","name":"mastrodicasa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"\/web\/#\/schema\/person\/image\/","url":"http:\/\/0.gravatar.com\/avatar\/3193e7cdcf94bcc77fa1c5b0cf49f5f6?s=96&d=mm&r=g","contentUrl":"http:\/\/0.gravatar.com\/avatar\/3193e7cdcf94bcc77fa1c5b0cf49f5f6?s=96&d=mm&r=g","caption":"mastrodicasa"},"url":"\/web\/author\/mastrodicasa\/"}]}},"_links":{"self":[{"href":"\/web\/wp-json\/wp\/v2\/posts\/375"}],"collection":[{"href":"\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"\/web\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"\/web\/wp-json\/wp\/v2\/comments?post=375"}],"version-history":[{"count":1,"href":"\/web\/wp-json\/wp\/v2\/posts\/375\/revisions"}],"predecessor-version":[{"id":378,"href":"\/web\/wp-json\/wp\/v2\/posts\/375\/revisions\/378"}],"wp:featuredmedia":[{"embeddable":true,"href":"\/web\/wp-json\/wp\/v2\/media\/376"}],"wp:attachment":[{"href":"\/web\/wp-json\/wp\/v2\/media?parent=375"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"\/web\/wp-json\/wp\/v2\/categories?post=375"},{"taxonomy":"post_tag","embeddable":true,"href":"\/web\/wp-json\/wp\/v2\/tags?post=375"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}