{"id":3647,"date":"2026-02-18T08:18:29","date_gmt":"2026-02-18T07:18:29","guid":{"rendered":"\/web\/?p=3647"},"modified":"2026-02-23T11:30:08","modified_gmt":"2026-02-23T10:30:08","slug":"case-della-salute-asl-to3-canalis-la-politica-si-fa-con-gli-atti-e-non-con-le-conferenze-stampa","status":"publish","type":"post","link":"\/web\/2026\/02\/18\/case-della-salute-asl-to3-canalis-la-politica-si-fa-con-gli-atti-e-non-con-le-conferenze-stampa\/","title":{"rendered":"CASE DELLA SALUTE ASL TO3. CANALIS: LA POLITICA SI FA CON GLI ATTI E NON CON LE CONFERENZE STAMPA."},"content":{"rendered":"\n<p><strong><em>Monitoreremo la tutela dei 22 lavoratori e la trasformazione in case della comunit\u00e0 spoke.<\/em><\/strong><\/p>\n\n\n\n<p>17.2.2026 &#8211; A novembre l\u2019ASL To3 minacciava la chiusura entro fine anno delle 4 Case della salute dell\u2019ASL To3, che dal primo gennaio dovevano essere retrocesse a semplici AFT, come testimoniato dalla lettera di La Valle del mese&nbsp;di novembre.&nbsp;Oggi&nbsp;invece, in conferenza stampa, Cirio e Riboldi hanno fatto una bella retromarcia, affermando di volerle trasformare in case della comunit\u00e0 spoke.<\/p>\n\n\n\n<p>Bene la retromarcia, ma ora dobbiamo essere sicuri che la trasformazione non sia un mero annuncio.<\/p>\n\n\n\n<p>Ad&nbsp;oggi&nbsp;infatti non c\u2019\u00e8 alcun atto formale, giuridicamente e finanziariamente vincolante.<\/p>\n\n\n\n<p>Il DM 77\/2022 prevede la creazione delle case della comunit\u00e0 spoke a fianco di quelle hub, per rendere pi\u00f9 capillare la medicina territoriale e sgravare gli ospedali, ma in Piemonte non ne \u00e8 ancora nata neppure una.<\/p>\n\n\n\n<p>Come mai?<\/p>\n\n\n\n<p>Queste strutture resteranno lettera morta?<\/p>\n\n\n\n<p>Cosa sta facendo concretamente la giunta Cirio?<\/p>\n\n\n\n<p>Sta sollecitando la conferenza stato-regioni?<\/p>\n\n\n\n<p>Ad&nbsp;oggi&nbsp;non \u00e8 dato saperlo.<\/p>\n\n\n\n<p>Cos\u00ec come non c\u2019\u00e8 assoluta certezza giuridica che i lavoratori rimasti in carico ai Medici di medicina generale (4 a Vigone, 3 a Cumiana, 7 a Beinasco e 3 a Pianezza) potranno proseguire, non essendoci un legame contrattuale diretto con l\u2019Asl.<\/p>\n\n\n\n<p>In particolare, preoccupa la situazione dei 9 lavoratori della casa della salute di Beinasco-Borgaretto, dal momento che in questa Casa i medici non si sono ancora costituiti in soggetto giuridico per contrattualizzare i lavoratori. Il risultato \u00e8 che 7 lavoratori sono ancora gestiti dalla cooperativa Coesa e non dai medici e 2 hanno lasciato il contratto a tempo indeterminato per essere assunti da un\u2019agenzia di lavoro interinale con un contratto peggiorativo.<\/p>\n\n\n\n<p>Ci saremmo aspettati che l\u2019ASL facesse di pi\u00f9 per subentrare nei contratti di questi lavoratori.<\/p>\n\n\n\n<p>Insomma: bene la conferenza stampa a favore di telecamera, ma la politica si fa con gli atti e gli atti mancano.<\/p>\n\n\n\n<p>Ad&nbsp;oggi, come temevamo, ci sono 4 case della salute trasformate in AFT.<\/p>\n\n\n\n<p><strong>Monica CANALIS \u2013 consigliera regionale PD<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Monitoreremo la tutela dei 22 lavoratori e la trasformazione in case della comunit\u00e0 spoke. 17.2.2026 &#8211; A novembre l\u2019ASL To3 minacciava la chiusura entro fine anno delle 4 Case della salute dell\u2019ASL To3, che dal primo gennaio dovevano essere retrocesse a semplici AFT, come testimoniato dalla lettera di La Valle del mese&nbsp;di novembre.&nbsp;Oggi&nbsp;invece, in conferenza [&hellip;]<\/p>\n","protected":false},"author":100,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[76],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.12 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>CASE DELLA SALUTE ASL TO3. CANALIS: LA POLITICA SI FA CON GLI ATTI E NON CON LE CONFERENZE STAMPA. - Partito Democratico<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"\/web\/2026\/02\/18\/case-della-salute-asl-to3-canalis-la-politica-si-fa-con-gli-atti-e-non-con-le-conferenze-stampa\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CASE DELLA SALUTE ASL TO3. CANALIS: LA POLITICA SI FA CON GLI ATTI E NON CON LE CONFERENZE STAMPA. - Partito Democratico\" \/>\n<meta property=\"og:description\" content=\"Monitoreremo la tutela dei 22 lavoratori e la trasformazione in case della comunit\u00e0 spoke. 17.2.2026 &#8211; A novembre l\u2019ASL To3 minacciava la chiusura entro fine anno delle 4 Case della salute dell\u2019ASL To3, che dal primo gennaio dovevano essere retrocesse a semplici AFT, come testimoniato dalla lettera di La Valle del mese&nbsp;di novembre.&nbsp;Oggi&nbsp;invece, in conferenza [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"\/web\/2026\/02\/18\/case-della-salute-asl-to3-canalis-la-politica-si-fa-con-gli-atti-e-non-con-le-conferenze-stampa\/\" \/>\n<meta property=\"og:site_name\" content=\"Partito Democratico\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-18T07:18:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-23T10:30:08+00:00\" \/>\n<meta name=\"author\" content=\"apuglisi\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"apuglisi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"\/web\/2026\/02\/18\/case-della-salute-asl-to3-canalis-la-politica-si-fa-con-gli-atti-e-non-con-le-conferenze-stampa\/\",\"url\":\"\/web\/2026\/02\/18\/case-della-salute-asl-to3-canalis-la-politica-si-fa-con-gli-atti-e-non-con-le-conferenze-stampa\/\",\"name\":\"CASE DELLA SALUTE ASL TO3. CANALIS: LA POLITICA SI FA CON GLI ATTI E NON CON LE CONFERENZE STAMPA. - Partito Democratico\",\"isPartOf\":{\"@id\":\"\/web\/#website\"},\"datePublished\":\"2026-02-18T07:18:29+00:00\",\"dateModified\":\"2026-02-23T10:30:08+00:00\",\"author\":{\"@id\":\"\/web\/#\/schema\/person\/0c13e972954f051ef0b6604dcdcd093a\"},\"breadcrumb\":{\"@id\":\"\/web\/2026\/02\/18\/case-della-salute-asl-to3-canalis-la-politica-si-fa-con-gli-atti-e-non-con-le-conferenze-stampa\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"\/web\/2026\/02\/18\/case-della-salute-asl-to3-canalis-la-politica-si-fa-con-gli-atti-e-non-con-le-conferenze-stampa\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"\/web\/2026\/02\/18\/case-della-salute-asl-to3-canalis-la-politica-si-fa-con-gli-atti-e-non-con-le-conferenze-stampa\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CASE DELLA SALUTE ASL TO3. CANALIS: LA POLITICA SI FA CON GLI ATTI E NON CON LE CONFERENZE STAMPA.\"}]},{\"@type\":\"WebSite\",\"@id\":\"\/web\/#website\",\"url\":\"\/web\/\",\"name\":\"Partito Democratico\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"\/web\/#\/schema\/person\/0c13e972954f051ef0b6604dcdcd093a\",\"name\":\"apuglisi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"\/web\/#\/schema\/person\/image\/\",\"url\":\"http:\/\/2.gravatar.com\/avatar\/8f77005929681ecacb724a762adbc06b?s=96&d=mm&r=g\",\"contentUrl\":\"http:\/\/2.gravatar.com\/avatar\/8f77005929681ecacb724a762adbc06b?s=96&d=mm&r=g\",\"caption\":\"apuglisi\"},\"url\":\"\/web\/author\/apuglisi\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CASE DELLA SALUTE ASL TO3. CANALIS: LA POLITICA SI FA CON GLI ATTI E NON CON LE CONFERENZE STAMPA. - Partito Democratico","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"\/web\/2026\/02\/18\/case-della-salute-asl-to3-canalis-la-politica-si-fa-con-gli-atti-e-non-con-le-conferenze-stampa\/","og_locale":"it_IT","og_type":"article","og_title":"CASE DELLA SALUTE ASL TO3. CANALIS: LA POLITICA SI FA CON GLI ATTI E NON CON LE CONFERENZE STAMPA. - Partito Democratico","og_description":"Monitoreremo la tutela dei 22 lavoratori e la trasformazione in case della comunit\u00e0 spoke. 17.2.2026 &#8211; A novembre l\u2019ASL To3 minacciava la chiusura entro fine anno delle 4 Case della salute dell\u2019ASL To3, che dal primo gennaio dovevano essere retrocesse a semplici AFT, come testimoniato dalla lettera di La Valle del mese&nbsp;di novembre.&nbsp;Oggi&nbsp;invece, in conferenza [&hellip;]","og_url":"\/web\/2026\/02\/18\/case-della-salute-asl-to3-canalis-la-politica-si-fa-con-gli-atti-e-non-con-le-conferenze-stampa\/","og_site_name":"Partito Democratico","article_published_time":"2026-02-18T07:18:29+00:00","article_modified_time":"2026-02-23T10:30:08+00:00","author":"apuglisi","twitter_misc":{"Scritto da":"apuglisi","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"\/web\/2026\/02\/18\/case-della-salute-asl-to3-canalis-la-politica-si-fa-con-gli-atti-e-non-con-le-conferenze-stampa\/","url":"\/web\/2026\/02\/18\/case-della-salute-asl-to3-canalis-la-politica-si-fa-con-gli-atti-e-non-con-le-conferenze-stampa\/","name":"CASE DELLA SALUTE ASL TO3. CANALIS: LA POLITICA SI FA CON GLI ATTI E NON CON LE CONFERENZE STAMPA. - Partito Democratico","isPartOf":{"@id":"\/web\/#website"},"datePublished":"2026-02-18T07:18:29+00:00","dateModified":"2026-02-23T10:30:08+00:00","author":{"@id":"\/web\/#\/schema\/person\/0c13e972954f051ef0b6604dcdcd093a"},"breadcrumb":{"@id":"\/web\/2026\/02\/18\/case-della-salute-asl-to3-canalis-la-politica-si-fa-con-gli-atti-e-non-con-le-conferenze-stampa\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["\/web\/2026\/02\/18\/case-della-salute-asl-to3-canalis-la-politica-si-fa-con-gli-atti-e-non-con-le-conferenze-stampa\/"]}]},{"@type":"BreadcrumbList","@id":"\/web\/2026\/02\/18\/case-della-salute-asl-to3-canalis-la-politica-si-fa-con-gli-atti-e-non-con-le-conferenze-stampa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"\/web\/"},{"@type":"ListItem","position":2,"name":"CASE DELLA SALUTE ASL TO3. CANALIS: LA POLITICA SI FA CON GLI ATTI E NON CON LE CONFERENZE STAMPA."}]},{"@type":"WebSite","@id":"\/web\/#website","url":"\/web\/","name":"Partito Democratico","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"\/web\/#\/schema\/person\/0c13e972954f051ef0b6604dcdcd093a","name":"apuglisi","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"\/web\/#\/schema\/person\/image\/","url":"http:\/\/2.gravatar.com\/avatar\/8f77005929681ecacb724a762adbc06b?s=96&d=mm&r=g","contentUrl":"http:\/\/2.gravatar.com\/avatar\/8f77005929681ecacb724a762adbc06b?s=96&d=mm&r=g","caption":"apuglisi"},"url":"\/web\/author\/apuglisi\/"}]}},"_links":{"self":[{"href":"\/web\/wp-json\/wp\/v2\/posts\/3647"}],"collection":[{"href":"\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"\/web\/wp-json\/wp\/v2\/users\/100"}],"replies":[{"embeddable":true,"href":"\/web\/wp-json\/wp\/v2\/comments?post=3647"}],"version-history":[{"count":1,"href":"\/web\/wp-json\/wp\/v2\/posts\/3647\/revisions"}],"predecessor-version":[{"id":3648,"href":"\/web\/wp-json\/wp\/v2\/posts\/3647\/revisions\/3648"}],"wp:attachment":[{"href":"\/web\/wp-json\/wp\/v2\/media?parent=3647"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"\/web\/wp-json\/wp\/v2\/categories?post=3647"},{"taxonomy":"post_tag","embeddable":true,"href":"\/web\/wp-json\/wp\/v2\/tags?post=3647"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}