{"id":3608,"date":"2026-02-04T10:57:19","date_gmt":"2026-02-04T09:57:19","guid":{"rendered":"\/web\/?p=3608"},"modified":"2026-02-23T11:42:59","modified_gmt":"2026-02-23T10:42:59","slug":"manca-il-numero-legale-in-consiglio-regionale-per-chi-governa-il-piemonte-la-sicurezza-puo-aspettare","status":"publish","type":"post","link":"\/web\/2026\/02\/04\/manca-il-numero-legale-in-consiglio-regionale-per-chi-governa-il-piemonte-la-sicurezza-puo-aspettare\/","title":{"rendered":"MANCA IL NUMERO LEGALE IN CONSIGLIO REGIONALE, PER CHI GOVERNA IL PIEMONTE LA SICUREZZA PUO\u2019 ASPETTARE"},"content":{"rendered":"\n<p>Ore 20.30. Manca il numero legale in Consiglio regionale durante la discussione degli ordini del giorno sul corteo di Askatasuna. Cade, cos\u00ec, anche la maschera di un Centrodestra che invece di discutere di sicurezza e tutela delle forze dell\u2019ordine &#8211; che etichettano sempre come prioritari &#8211; preferisce andare a cena e disertare la seduta a Palazzo Lascaris.&nbsp;<\/p>\n\n\n\n<p>A Roma la Destra chiede l\u2019unit\u00e0 delle forze politiche su una risoluzione comune, in prima serata attacca chi ha partecipato al corteo, e intanto in Piemonte non \u00e8 in grado di garantire nemmeno la prosecuzione del dibattito e il voto degli ordini del giorno. Un fatto grave e censurabile, che non permette alla politica di esprimere una condanna per i fatti del 31 gennaio, sui quali peraltro le minoranze hanno presentato ben tre atti di indirizzo.&nbsp;<\/p>\n\n\n\n<p>Dovremo attendere una settimana per riprendere la discussione: questa \u00e8 la seriet\u00e0 della maggioranza. Tanto, per chi governa il Piemonte, la sicurezza pu\u00f2 aspettare.&nbsp;<\/p>\n\n\n\n<p>Gianna Pentenero, presidente Pd&nbsp;<\/p>\n\n\n\n<p>Alice Ravinale, presidente Avs&nbsp;<\/p>\n\n\n\n<p>Sarah Disabato, presidente M5S<\/p>\n\n\n\n<p>Vittoria Nallo, presidente SUE<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ore 20.30. Manca il numero legale in Consiglio regionale durante la discussione degli ordini del giorno sul corteo di Askatasuna. Cade, cos\u00ec, anche la maschera di un Centrodestra che invece di discutere di sicurezza e tutela delle forze dell\u2019ordine &#8211; che etichettano sempre come prioritari &#8211; preferisce andare a cena e disertare la seduta a [&hellip;]<\/p>\n","protected":false},"author":100,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[4,22,58],"tags":[70],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.12 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>MANCA IL NUMERO LEGALE IN CONSIGLIO REGIONALE, PER CHI GOVERNA IL PIEMONTE LA SICUREZZA PUO\u2019 ASPETTARE - Partito Democratico<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"\/web\/2026\/02\/04\/manca-il-numero-legale-in-consiglio-regionale-per-chi-governa-il-piemonte-la-sicurezza-puo-aspettare\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MANCA IL NUMERO LEGALE IN CONSIGLIO REGIONALE, PER CHI GOVERNA IL PIEMONTE LA SICUREZZA PUO\u2019 ASPETTARE - Partito Democratico\" \/>\n<meta property=\"og:description\" content=\"Ore 20.30. Manca il numero legale in Consiglio regionale durante la discussione degli ordini del giorno sul corteo di Askatasuna. Cade, cos\u00ec, anche la maschera di un Centrodestra che invece di discutere di sicurezza e tutela delle forze dell\u2019ordine &#8211; che etichettano sempre come prioritari &#8211; preferisce andare a cena e disertare la seduta a [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"\/web\/2026\/02\/04\/manca-il-numero-legale-in-consiglio-regionale-per-chi-governa-il-piemonte-la-sicurezza-puo-aspettare\/\" \/>\n<meta property=\"og:site_name\" content=\"Partito Democratico\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-04T09:57:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-23T10:42:59+00:00\" \/>\n<meta name=\"author\" content=\"apuglisi\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"apuglisi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"\/web\/2026\/02\/04\/manca-il-numero-legale-in-consiglio-regionale-per-chi-governa-il-piemonte-la-sicurezza-puo-aspettare\/\",\"url\":\"\/web\/2026\/02\/04\/manca-il-numero-legale-in-consiglio-regionale-per-chi-governa-il-piemonte-la-sicurezza-puo-aspettare\/\",\"name\":\"MANCA IL NUMERO LEGALE IN CONSIGLIO REGIONALE, PER CHI GOVERNA IL PIEMONTE LA SICUREZZA PUO\u2019 ASPETTARE - Partito Democratico\",\"isPartOf\":{\"@id\":\"\/web\/#website\"},\"datePublished\":\"2026-02-04T09:57:19+00:00\",\"dateModified\":\"2026-02-23T10:42:59+00:00\",\"author\":{\"@id\":\"\/web\/#\/schema\/person\/0c13e972954f051ef0b6604dcdcd093a\"},\"breadcrumb\":{\"@id\":\"\/web\/2026\/02\/04\/manca-il-numero-legale-in-consiglio-regionale-per-chi-governa-il-piemonte-la-sicurezza-puo-aspettare\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"\/web\/2026\/02\/04\/manca-il-numero-legale-in-consiglio-regionale-per-chi-governa-il-piemonte-la-sicurezza-puo-aspettare\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"\/web\/2026\/02\/04\/manca-il-numero-legale-in-consiglio-regionale-per-chi-governa-il-piemonte-la-sicurezza-puo-aspettare\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"MANCA IL NUMERO LEGALE IN CONSIGLIO REGIONALE, PER CHI GOVERNA IL PIEMONTE LA SICUREZZA PUO\u2019 ASPETTARE\"}]},{\"@type\":\"WebSite\",\"@id\":\"\/web\/#website\",\"url\":\"\/web\/\",\"name\":\"Partito Democratico\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"\/web\/#\/schema\/person\/0c13e972954f051ef0b6604dcdcd093a\",\"name\":\"apuglisi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"\/web\/#\/schema\/person\/image\/\",\"url\":\"http:\/\/2.gravatar.com\/avatar\/8f77005929681ecacb724a762adbc06b?s=96&d=mm&r=g\",\"contentUrl\":\"http:\/\/2.gravatar.com\/avatar\/8f77005929681ecacb724a762adbc06b?s=96&d=mm&r=g\",\"caption\":\"apuglisi\"},\"url\":\"\/web\/author\/apuglisi\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MANCA IL NUMERO LEGALE IN CONSIGLIO REGIONALE, PER CHI GOVERNA IL PIEMONTE LA SICUREZZA PUO\u2019 ASPETTARE - Partito Democratico","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"\/web\/2026\/02\/04\/manca-il-numero-legale-in-consiglio-regionale-per-chi-governa-il-piemonte-la-sicurezza-puo-aspettare\/","og_locale":"it_IT","og_type":"article","og_title":"MANCA IL NUMERO LEGALE IN CONSIGLIO REGIONALE, PER CHI GOVERNA IL PIEMONTE LA SICUREZZA PUO\u2019 ASPETTARE - Partito Democratico","og_description":"Ore 20.30. Manca il numero legale in Consiglio regionale durante la discussione degli ordini del giorno sul corteo di Askatasuna. Cade, cos\u00ec, anche la maschera di un Centrodestra che invece di discutere di sicurezza e tutela delle forze dell\u2019ordine &#8211; che etichettano sempre come prioritari &#8211; preferisce andare a cena e disertare la seduta a [&hellip;]","og_url":"\/web\/2026\/02\/04\/manca-il-numero-legale-in-consiglio-regionale-per-chi-governa-il-piemonte-la-sicurezza-puo-aspettare\/","og_site_name":"Partito Democratico","article_published_time":"2026-02-04T09:57:19+00:00","article_modified_time":"2026-02-23T10:42:59+00:00","author":"apuglisi","twitter_misc":{"Scritto da":"apuglisi","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"\/web\/2026\/02\/04\/manca-il-numero-legale-in-consiglio-regionale-per-chi-governa-il-piemonte-la-sicurezza-puo-aspettare\/","url":"\/web\/2026\/02\/04\/manca-il-numero-legale-in-consiglio-regionale-per-chi-governa-il-piemonte-la-sicurezza-puo-aspettare\/","name":"MANCA IL NUMERO LEGALE IN CONSIGLIO REGIONALE, PER CHI GOVERNA IL PIEMONTE LA SICUREZZA PUO\u2019 ASPETTARE - Partito Democratico","isPartOf":{"@id":"\/web\/#website"},"datePublished":"2026-02-04T09:57:19+00:00","dateModified":"2026-02-23T10:42:59+00:00","author":{"@id":"\/web\/#\/schema\/person\/0c13e972954f051ef0b6604dcdcd093a"},"breadcrumb":{"@id":"\/web\/2026\/02\/04\/manca-il-numero-legale-in-consiglio-regionale-per-chi-governa-il-piemonte-la-sicurezza-puo-aspettare\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["\/web\/2026\/02\/04\/manca-il-numero-legale-in-consiglio-regionale-per-chi-governa-il-piemonte-la-sicurezza-puo-aspettare\/"]}]},{"@type":"BreadcrumbList","@id":"\/web\/2026\/02\/04\/manca-il-numero-legale-in-consiglio-regionale-per-chi-governa-il-piemonte-la-sicurezza-puo-aspettare\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"\/web\/"},{"@type":"ListItem","position":2,"name":"MANCA IL NUMERO LEGALE IN CONSIGLIO REGIONALE, PER CHI GOVERNA IL PIEMONTE LA SICUREZZA PUO\u2019 ASPETTARE"}]},{"@type":"WebSite","@id":"\/web\/#website","url":"\/web\/","name":"Partito Democratico","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"\/web\/#\/schema\/person\/0c13e972954f051ef0b6604dcdcd093a","name":"apuglisi","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"\/web\/#\/schema\/person\/image\/","url":"http:\/\/2.gravatar.com\/avatar\/8f77005929681ecacb724a762adbc06b?s=96&d=mm&r=g","contentUrl":"http:\/\/2.gravatar.com\/avatar\/8f77005929681ecacb724a762adbc06b?s=96&d=mm&r=g","caption":"apuglisi"},"url":"\/web\/author\/apuglisi\/"}]}},"_links":{"self":[{"href":"\/web\/wp-json\/wp\/v2\/posts\/3608"}],"collection":[{"href":"\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"\/web\/wp-json\/wp\/v2\/users\/100"}],"replies":[{"embeddable":true,"href":"\/web\/wp-json\/wp\/v2\/comments?post=3608"}],"version-history":[{"count":1,"href":"\/web\/wp-json\/wp\/v2\/posts\/3608\/revisions"}],"predecessor-version":[{"id":3609,"href":"\/web\/wp-json\/wp\/v2\/posts\/3608\/revisions\/3609"}],"wp:attachment":[{"href":"\/web\/wp-json\/wp\/v2\/media?parent=3608"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"\/web\/wp-json\/wp\/v2\/categories?post=3608"},{"taxonomy":"post_tag","embeddable":true,"href":"\/web\/wp-json\/wp\/v2\/tags?post=3608"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}