{"id":3541,"date":"2025-07-23T12:05:44","date_gmt":"2025-07-23T10:05:44","guid":{"rendered":"\/web\/?p=3541"},"modified":"2025-07-23T12:05:47","modified_gmt":"2025-07-23T10:05:47","slug":"il-governo-introduce-lirpef-sulle-borse-di-ricerca","status":"publish","type":"post","link":"\/web\/2025\/07\/23\/il-governo-introduce-lirpef-sulle-borse-di-ricerca\/","title":{"rendered":"IL GOVERNO INTRODUCE L\u2019IRPEF SULLE BORSE DI RICERCA"},"content":{"rendered":"\n<p><strong>\u00abIl Governo Meloni ha cancellato l\u2019esenzione IRPEF per le borse di studio destinate ad attivit\u00e0 di ricerca post-laurea. Il che comporta una riduzione netta fino al 25% del valore mensile delle borse di ricerca,<\/strong>\u00a0generando un impatto economico significativo su centinaia di ricercatori e ricercatrici in tutto il Paese, e anche negli atenei piemontesi, spesso gi\u00e0 in condizioni di forte precariet\u00e0 e compensi insufficienti. Donne e uomini che guadagnano 1000 euro al mese e che, a causa della tassazione, diventano ora 750 euro al mese. Lavoratrici e lavoratori per lo pi\u00f9 precari, non contrattualizzati, che pur svolgendo un compito fondamentale per dare un futuro al nostro Paese non sono mai stati valorizzati ed ora con questa manovra vengono addirittura puniti.\u00a0<strong>La Giunta Cirio deve attivarsi affinch\u00e9 il Governo ritiri questa misura incomprensibile,\u00a0<\/strong>che spinger\u00e0 ancor di pi\u00f9 tanti \u201ccervelli\u201d, formati nelle nostre universit\u00e0 pubbliche, a lasciare l\u2019Italia. Il Piemonte ospita importanti atenei ed \u00e8 nostro dovere tutelare le ricercatrici e i ricercatori, incentivandoli a restare, ad esempio\u00a0<strong>istituendo in Piemonte un fondo per la ricerca precaria,\u00a0<\/strong>finalizzato sia a fornire integrazioni economiche per mitigare gli effetti della tassazione introdotta con legge n. 79 del 5 giugno 2025 sia a sostenere progetti di ricerca strategici con attenzione prioritaria alle giovani ricercatrici e ricercatori non strutturati, in condizioni di particolare vulnerabilit\u00e0 contrattuale ed economica<strong>\u00bb.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abIl Governo Meloni ha cancellato l\u2019esenzione IRPEF per le borse di studio destinate ad attivit\u00e0 di ricerca post-laurea. Il che comporta una riduzione netta fino al 25% del valore mensile delle borse di ricerca,\u00a0generando un impatto economico significativo su centinaia di ricercatori e ricercatrici in tutto il Paese, e anche negli atenei piemontesi, spesso gi\u00e0 [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.12 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>IL GOVERNO INTRODUCE L\u2019IRPEF SULLE BORSE DI RICERCA - Partito Democratico<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"\/web\/2025\/07\/23\/il-governo-introduce-lirpef-sulle-borse-di-ricerca\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"IL GOVERNO INTRODUCE L\u2019IRPEF SULLE BORSE DI RICERCA - Partito Democratico\" \/>\n<meta property=\"og:description\" content=\"\u00abIl Governo Meloni ha cancellato l\u2019esenzione IRPEF per le borse di studio destinate ad attivit\u00e0 di ricerca post-laurea. Il che comporta una riduzione netta fino al 25% del valore mensile delle borse di ricerca,\u00a0generando un impatto economico significativo su centinaia di ricercatori e ricercatrici in tutto il Paese, e anche negli atenei piemontesi, spesso gi\u00e0 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"\/web\/2025\/07\/23\/il-governo-introduce-lirpef-sulle-borse-di-ricerca\/\" \/>\n<meta property=\"og:site_name\" content=\"Partito Democratico\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-23T10:05:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-23T10:05:47+00:00\" \/>\n<meta name=\"author\" content=\"mastrodicasa\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"mastrodicasa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"\/web\/2025\/07\/23\/il-governo-introduce-lirpef-sulle-borse-di-ricerca\/\",\"url\":\"\/web\/2025\/07\/23\/il-governo-introduce-lirpef-sulle-borse-di-ricerca\/\",\"name\":\"IL GOVERNO INTRODUCE L\u2019IRPEF SULLE BORSE DI RICERCA - Partito Democratico\",\"isPartOf\":{\"@id\":\"\/web\/#website\"},\"datePublished\":\"2025-07-23T10:05:44+00:00\",\"dateModified\":\"2025-07-23T10:05:47+00:00\",\"author\":{\"@id\":\"\/web\/#\/schema\/person\/e3213afc750e7648b3ad0561ab389690\"},\"breadcrumb\":{\"@id\":\"\/web\/2025\/07\/23\/il-governo-introduce-lirpef-sulle-borse-di-ricerca\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"\/web\/2025\/07\/23\/il-governo-introduce-lirpef-sulle-borse-di-ricerca\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"\/web\/2025\/07\/23\/il-governo-introduce-lirpef-sulle-borse-di-ricerca\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"IL GOVERNO INTRODUCE L\u2019IRPEF SULLE BORSE DI RICERCA\"}]},{\"@type\":\"WebSite\",\"@id\":\"\/web\/#website\",\"url\":\"\/web\/\",\"name\":\"Partito Democratico\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"\/web\/#\/schema\/person\/e3213afc750e7648b3ad0561ab389690\",\"name\":\"mastrodicasa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"\/web\/#\/schema\/person\/image\/\",\"url\":\"http:\/\/0.gravatar.com\/avatar\/3193e7cdcf94bcc77fa1c5b0cf49f5f6?s=96&d=mm&r=g\",\"contentUrl\":\"http:\/\/0.gravatar.com\/avatar\/3193e7cdcf94bcc77fa1c5b0cf49f5f6?s=96&d=mm&r=g\",\"caption\":\"mastrodicasa\"},\"url\":\"\/web\/author\/mastrodicasa\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"IL GOVERNO INTRODUCE L\u2019IRPEF SULLE BORSE DI RICERCA - Partito Democratico","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"\/web\/2025\/07\/23\/il-governo-introduce-lirpef-sulle-borse-di-ricerca\/","og_locale":"it_IT","og_type":"article","og_title":"IL GOVERNO INTRODUCE L\u2019IRPEF SULLE BORSE DI RICERCA - Partito Democratico","og_description":"\u00abIl Governo Meloni ha cancellato l\u2019esenzione IRPEF per le borse di studio destinate ad attivit\u00e0 di ricerca post-laurea. Il che comporta una riduzione netta fino al 25% del valore mensile delle borse di ricerca,\u00a0generando un impatto economico significativo su centinaia di ricercatori e ricercatrici in tutto il Paese, e anche negli atenei piemontesi, spesso gi\u00e0 [&hellip;]","og_url":"\/web\/2025\/07\/23\/il-governo-introduce-lirpef-sulle-borse-di-ricerca\/","og_site_name":"Partito Democratico","article_published_time":"2025-07-23T10:05:44+00:00","article_modified_time":"2025-07-23T10:05:47+00:00","author":"mastrodicasa","twitter_misc":{"Scritto da":"mastrodicasa","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"\/web\/2025\/07\/23\/il-governo-introduce-lirpef-sulle-borse-di-ricerca\/","url":"\/web\/2025\/07\/23\/il-governo-introduce-lirpef-sulle-borse-di-ricerca\/","name":"IL GOVERNO INTRODUCE L\u2019IRPEF SULLE BORSE DI RICERCA - Partito Democratico","isPartOf":{"@id":"\/web\/#website"},"datePublished":"2025-07-23T10:05:44+00:00","dateModified":"2025-07-23T10:05:47+00:00","author":{"@id":"\/web\/#\/schema\/person\/e3213afc750e7648b3ad0561ab389690"},"breadcrumb":{"@id":"\/web\/2025\/07\/23\/il-governo-introduce-lirpef-sulle-borse-di-ricerca\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["\/web\/2025\/07\/23\/il-governo-introduce-lirpef-sulle-borse-di-ricerca\/"]}]},{"@type":"BreadcrumbList","@id":"\/web\/2025\/07\/23\/il-governo-introduce-lirpef-sulle-borse-di-ricerca\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"\/web\/"},{"@type":"ListItem","position":2,"name":"IL GOVERNO INTRODUCE L\u2019IRPEF SULLE BORSE DI RICERCA"}]},{"@type":"WebSite","@id":"\/web\/#website","url":"\/web\/","name":"Partito Democratico","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"\/web\/#\/schema\/person\/e3213afc750e7648b3ad0561ab389690","name":"mastrodicasa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"\/web\/#\/schema\/person\/image\/","url":"http:\/\/0.gravatar.com\/avatar\/3193e7cdcf94bcc77fa1c5b0cf49f5f6?s=96&d=mm&r=g","contentUrl":"http:\/\/0.gravatar.com\/avatar\/3193e7cdcf94bcc77fa1c5b0cf49f5f6?s=96&d=mm&r=g","caption":"mastrodicasa"},"url":"\/web\/author\/mastrodicasa\/"}]}},"_links":{"self":[{"href":"\/web\/wp-json\/wp\/v2\/posts\/3541"}],"collection":[{"href":"\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"\/web\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"\/web\/wp-json\/wp\/v2\/comments?post=3541"}],"version-history":[{"count":2,"href":"\/web\/wp-json\/wp\/v2\/posts\/3541\/revisions"}],"predecessor-version":[{"id":3543,"href":"\/web\/wp-json\/wp\/v2\/posts\/3541\/revisions\/3543"}],"wp:attachment":[{"href":"\/web\/wp-json\/wp\/v2\/media?parent=3541"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"\/web\/wp-json\/wp\/v2\/categories?post=3541"},{"taxonomy":"post_tag","embeddable":true,"href":"\/web\/wp-json\/wp\/v2\/tags?post=3541"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}