{"id":3524,"date":"2025-07-17T10:40:42","date_gmt":"2025-07-17T08:40:42","guid":{"rendered":"\/web\/?p=3524"},"modified":"2025-07-17T10:40:46","modified_gmt":"2025-07-17T08:40:46","slug":"trasporto-pubblico-confermato-in-consiglio-il-taglio-di-23-milioni-per-il-piemonte","status":"publish","type":"post","link":"\/web\/2025\/07\/17\/trasporto-pubblico-confermato-in-consiglio-il-taglio-di-23-milioni-per-il-piemonte\/","title":{"rendered":"<strong>TRASPORTO PUBBLICO: CONFERMATO IN CONSIGLIO IL TAGLIO DI 23 MILIONI PER IL PIEMONTE<\/strong>"},"content":{"rendered":"\n<p>&#8220;L\u2019Assessore ai Trasporti della Regione Piemonte ha confermato oggi in Aula quanto temevamo da settimane: il Fondo Nazionale per il Trasporto Pubblico Locale subir\u00e0 un taglio di almeno 23 milioni di euro per il Piemonte, a seguito della nuova ripartizione ministeriale basata sui cosiddetti Livelli Adeguati di Servizio (LAS). \u00c8 un colpo durissimo per la nostra Regione, gi\u00e0 alle prese con un sistema di trasporti fragile, fatto di corse soppresse, mezzi obsoleti e territori isolati. Questo taglio segna l&#8217;inizio dello smantellamento del servizio pubblico di mobilit\u00e0&#8221;.<\/p>\n\n\n\n<p><strong>Lo dichiarano i consiglieri regionali Nadia Conticelli (PD) e Alberto Unia (M5S).<\/strong><\/p>\n\n\n\n<p>&#8220;Il Governo nazionale premia le Regioni considerate &#8220;virtuose&#8221;, penalizzando quelle in difficolt\u00e0, senza tenere conto dei contesti territoriali o delle scelte del passato. Il Piemonte, fanalino di coda in questa classifica, paga un prezzo altissimo. Meno 23 milioni significa meno autobus, meno treni, meno corse. A farne le spese saranno soprattutto pendolari, studenti, lavoratori, anziani e intere comunit\u00e0 gi\u00e0 oggi escluse dal diritto alla mobilit\u00e0&#8221; proseguono i consiglieri.<\/p>\n\n\n\n<p>&#8220;Il taglio arriva in un momento particolarmente delicato: proprio ora si stanno avviando le gare per il nuovo affidamento del TPL nelle aree metropolitane, a partire da Torino e Cuneo &#8211; sottolineano ancora &#8211; . In questo contesto, misure come gli abbonamenti &#8216;Formula&#8217; per gli studenti rischiano di saltare. La proposta della Regione sul trasporto gratuito per gli universitari su Torino \u00e8 positiva, ma non basta: non si pu\u00f2 coprire un buco di 23 milioni con un&#8217;iniziativa parziale&#8221;.<\/p>\n\n\n\n<p>&#8220;Sul nodo torinese sono in corso investimenti infrastrutturali strategici: la nuova linea ferroviaria SFM5, i collegamenti con l\u2019aeroporto, il prolungamento della metropolitana, la futura linea 2 e la linea tramviaria 12. Ma chi garantir\u00e0 i costi di esercizio di queste opere una volta completate? Non basta prendere atto dei tagli. \u00c8 necessario verificare i criteri adottati dal Ministero, fare chiarezza sui conti della Regione e pretendere giustizia per il Piemonte \u2013 affermano Conticelli e Unia \u2013. Ad esempio, le linee ferroviarie dismesse sono state conteggiate nel calcolo dei LAS? E con quale logica?&nbsp;Il rischio \u00e8 che a pagare il prezzo di queste scelte siano ancora una volta i cittadini pi\u00f9 fragili, proprio mentre si dovrebbe rafforzare il trasporto pubblico come leva di giustizia sociale, sostenibilit\u00e0 ambientale e sviluppo locale&#8221;.<\/p>\n\n\n\n<p><strong>Conticelli e Unia chiedono alla Giunta regionale di attivarsi subito, con urgenza, sia a livello tecnico che politico, per scongiurare una riduzione dei servizi e garantire risorse adeguate a un diritto fondamentale come la mobilit\u00e0.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;L\u2019Assessore ai Trasporti della Regione Piemonte ha confermato oggi in Aula quanto temevamo da settimane: il Fondo Nazionale per il Trasporto Pubblico Locale subir\u00e0 un taglio di almeno 23 milioni di euro per il Piemonte, a seguito della nuova ripartizione ministeriale basata sui cosiddetti Livelli Adeguati di Servizio (LAS). \u00c8 un colpo durissimo per la [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[60],"tags":[44],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.12 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>TRASPORTO PUBBLICO: CONFERMATO IN CONSIGLIO IL TAGLIO DI 23 MILIONI PER IL PIEMONTE - Partito Democratico<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"\/web\/2025\/07\/17\/trasporto-pubblico-confermato-in-consiglio-il-taglio-di-23-milioni-per-il-piemonte\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"TRASPORTO PUBBLICO: CONFERMATO IN CONSIGLIO IL TAGLIO DI 23 MILIONI PER IL PIEMONTE - Partito Democratico\" \/>\n<meta property=\"og:description\" content=\"&#8220;L\u2019Assessore ai Trasporti della Regione Piemonte ha confermato oggi in Aula quanto temevamo da settimane: il Fondo Nazionale per il Trasporto Pubblico Locale subir\u00e0 un taglio di almeno 23 milioni di euro per il Piemonte, a seguito della nuova ripartizione ministeriale basata sui cosiddetti Livelli Adeguati di Servizio (LAS). \u00c8 un colpo durissimo per la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"\/web\/2025\/07\/17\/trasporto-pubblico-confermato-in-consiglio-il-taglio-di-23-milioni-per-il-piemonte\/\" \/>\n<meta property=\"og:site_name\" content=\"Partito Democratico\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-17T08:40:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-17T08:40:46+00:00\" \/>\n<meta name=\"author\" content=\"mastrodicasa\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"mastrodicasa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"\/web\/2025\/07\/17\/trasporto-pubblico-confermato-in-consiglio-il-taglio-di-23-milioni-per-il-piemonte\/\",\"url\":\"\/web\/2025\/07\/17\/trasporto-pubblico-confermato-in-consiglio-il-taglio-di-23-milioni-per-il-piemonte\/\",\"name\":\"TRASPORTO PUBBLICO: CONFERMATO IN CONSIGLIO IL TAGLIO DI 23 MILIONI PER IL PIEMONTE - Partito Democratico\",\"isPartOf\":{\"@id\":\"\/web\/#website\"},\"datePublished\":\"2025-07-17T08:40:42+00:00\",\"dateModified\":\"2025-07-17T08:40:46+00:00\",\"author\":{\"@id\":\"\/web\/#\/schema\/person\/e3213afc750e7648b3ad0561ab389690\"},\"breadcrumb\":{\"@id\":\"\/web\/2025\/07\/17\/trasporto-pubblico-confermato-in-consiglio-il-taglio-di-23-milioni-per-il-piemonte\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"\/web\/2025\/07\/17\/trasporto-pubblico-confermato-in-consiglio-il-taglio-di-23-milioni-per-il-piemonte\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"\/web\/2025\/07\/17\/trasporto-pubblico-confermato-in-consiglio-il-taglio-di-23-milioni-per-il-piemonte\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"TRASPORTO PUBBLICO: CONFERMATO IN CONSIGLIO IL TAGLIO DI 23 MILIONI PER IL PIEMONTE\"}]},{\"@type\":\"WebSite\",\"@id\":\"\/web\/#website\",\"url\":\"\/web\/\",\"name\":\"Partito Democratico\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"\/web\/#\/schema\/person\/e3213afc750e7648b3ad0561ab389690\",\"name\":\"mastrodicasa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"\/web\/#\/schema\/person\/image\/\",\"url\":\"http:\/\/0.gravatar.com\/avatar\/3193e7cdcf94bcc77fa1c5b0cf49f5f6?s=96&d=mm&r=g\",\"contentUrl\":\"http:\/\/0.gravatar.com\/avatar\/3193e7cdcf94bcc77fa1c5b0cf49f5f6?s=96&d=mm&r=g\",\"caption\":\"mastrodicasa\"},\"url\":\"\/web\/author\/mastrodicasa\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"TRASPORTO PUBBLICO: CONFERMATO IN CONSIGLIO IL TAGLIO DI 23 MILIONI PER IL PIEMONTE - Partito Democratico","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"\/web\/2025\/07\/17\/trasporto-pubblico-confermato-in-consiglio-il-taglio-di-23-milioni-per-il-piemonte\/","og_locale":"it_IT","og_type":"article","og_title":"TRASPORTO PUBBLICO: CONFERMATO IN CONSIGLIO IL TAGLIO DI 23 MILIONI PER IL PIEMONTE - Partito Democratico","og_description":"&#8220;L\u2019Assessore ai Trasporti della Regione Piemonte ha confermato oggi in Aula quanto temevamo da settimane: il Fondo Nazionale per il Trasporto Pubblico Locale subir\u00e0 un taglio di almeno 23 milioni di euro per il Piemonte, a seguito della nuova ripartizione ministeriale basata sui cosiddetti Livelli Adeguati di Servizio (LAS). \u00c8 un colpo durissimo per la [&hellip;]","og_url":"\/web\/2025\/07\/17\/trasporto-pubblico-confermato-in-consiglio-il-taglio-di-23-milioni-per-il-piemonte\/","og_site_name":"Partito Democratico","article_published_time":"2025-07-17T08:40:42+00:00","article_modified_time":"2025-07-17T08:40:46+00:00","author":"mastrodicasa","twitter_misc":{"Scritto da":"mastrodicasa","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"\/web\/2025\/07\/17\/trasporto-pubblico-confermato-in-consiglio-il-taglio-di-23-milioni-per-il-piemonte\/","url":"\/web\/2025\/07\/17\/trasporto-pubblico-confermato-in-consiglio-il-taglio-di-23-milioni-per-il-piemonte\/","name":"TRASPORTO PUBBLICO: CONFERMATO IN CONSIGLIO IL TAGLIO DI 23 MILIONI PER IL PIEMONTE - Partito Democratico","isPartOf":{"@id":"\/web\/#website"},"datePublished":"2025-07-17T08:40:42+00:00","dateModified":"2025-07-17T08:40:46+00:00","author":{"@id":"\/web\/#\/schema\/person\/e3213afc750e7648b3ad0561ab389690"},"breadcrumb":{"@id":"\/web\/2025\/07\/17\/trasporto-pubblico-confermato-in-consiglio-il-taglio-di-23-milioni-per-il-piemonte\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["\/web\/2025\/07\/17\/trasporto-pubblico-confermato-in-consiglio-il-taglio-di-23-milioni-per-il-piemonte\/"]}]},{"@type":"BreadcrumbList","@id":"\/web\/2025\/07\/17\/trasporto-pubblico-confermato-in-consiglio-il-taglio-di-23-milioni-per-il-piemonte\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"\/web\/"},{"@type":"ListItem","position":2,"name":"TRASPORTO PUBBLICO: CONFERMATO IN CONSIGLIO IL TAGLIO DI 23 MILIONI PER IL PIEMONTE"}]},{"@type":"WebSite","@id":"\/web\/#website","url":"\/web\/","name":"Partito Democratico","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"\/web\/#\/schema\/person\/e3213afc750e7648b3ad0561ab389690","name":"mastrodicasa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"\/web\/#\/schema\/person\/image\/","url":"http:\/\/0.gravatar.com\/avatar\/3193e7cdcf94bcc77fa1c5b0cf49f5f6?s=96&d=mm&r=g","contentUrl":"http:\/\/0.gravatar.com\/avatar\/3193e7cdcf94bcc77fa1c5b0cf49f5f6?s=96&d=mm&r=g","caption":"mastrodicasa"},"url":"\/web\/author\/mastrodicasa\/"}]}},"_links":{"self":[{"href":"\/web\/wp-json\/wp\/v2\/posts\/3524"}],"collection":[{"href":"\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"\/web\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"\/web\/wp-json\/wp\/v2\/comments?post=3524"}],"version-history":[{"count":1,"href":"\/web\/wp-json\/wp\/v2\/posts\/3524\/revisions"}],"predecessor-version":[{"id":3525,"href":"\/web\/wp-json\/wp\/v2\/posts\/3524\/revisions\/3525"}],"wp:attachment":[{"href":"\/web\/wp-json\/wp\/v2\/media?parent=3524"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"\/web\/wp-json\/wp\/v2\/categories?post=3524"},{"taxonomy":"post_tag","embeddable":true,"href":"\/web\/wp-json\/wp\/v2\/tags?post=3524"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}