{"id":3446,"date":"2025-04-14T12:44:28","date_gmt":"2025-04-14T10:44:28","guid":{"rendered":"\/web\/?p=3446"},"modified":"2025-04-14T12:44:31","modified_gmt":"2025-04-14T10:44:31","slug":"metro-due-parte-la-piu-grande-opera-infrastrutturale-dellarea-metropolitana","status":"publish","type":"post","link":"\/web\/2025\/04\/14\/metro-due-parte-la-piu-grande-opera-infrastrutturale-dellarea-metropolitana\/","title":{"rendered":"METRO DUE: PARTE LA PI\u00d9 GRANDE OPERA INFRASTRUTTURALE DELL\u2019AREA METROPOLITANA"},"content":{"rendered":"\n<p>&#8220;La gara per la realizzazione della metro due \u00e8 l\u2019avvio concreto di questa importante infrastruttura trasportistica di livello regionale e della pi\u00f9 grande opera di riqualificazione e di sviluppo dell\u2019area nord della citt\u00e0 di Torino.<\/p>\n\n\n\n<p>&#8220;Ho chiesto la convocazione in seduta congiunta delle<br>Commissioni Trasporti regionale e comunale proprio per sottolinearne la valenza regionale, con finanziamento interamente pubblico, frutto dello sforzo congiunto e trasversale, che si \u00e8 protratto nel tempo a prescindere dal cambio della colorazione politica dei governi che si sono succeduti. Quest&#8217;opera arriver\u00e0 al fondo solo se ciascuno far\u00e0 la sua parte.<\/p>\n\n\n\n<p>Sar\u00e0 il primo collegamento diretto fra le Universit\u00e0 (Manifattura Tabacchi, Campus e Palazzo Nuovo, Politecnico) e alcuni importanti siti poli industriali, da Pescarito a Lingotto.<\/p>\n\n\n\n<p>Ma soprattutto la metro 2 \u00e8 l\u2019approdo di una lunga battaglia dei cittadini di Torino nord lunga quasi quindici anni.<\/p>\n\n\n\n<p>Al netto di alcune pretestuose polemiche negli ultimi mesi, confido che entro la conclusione del tratto fino a Porta Nuova arrivino i fondi per arrivare al Politecnico e poi per la progettazione del secondo tratto fino ad Anselmetti e per i due fiotti verso Orbassano e verso San Mauro e Settimo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;La gara per la realizzazione della metro due \u00e8 l\u2019avvio concreto di questa importante infrastruttura trasportistica di livello regionale e della pi\u00f9 grande opera di riqualificazione e di sviluppo dell\u2019area nord della citt\u00e0 di Torino. &#8220;Ho chiesto la convocazione in seduta congiunta delleCommissioni Trasporti regionale e comunale proprio per sottolinearne la valenza regionale, con finanziamento [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.12 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>METRO DUE: PARTE LA PI\u00d9 GRANDE OPERA INFRASTRUTTURALE DELL\u2019AREA METROPOLITANA - Partito Democratico<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"\/web\/2025\/04\/14\/metro-due-parte-la-piu-grande-opera-infrastrutturale-dellarea-metropolitana\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"METRO DUE: PARTE LA PI\u00d9 GRANDE OPERA INFRASTRUTTURALE DELL\u2019AREA METROPOLITANA - Partito Democratico\" \/>\n<meta property=\"og:description\" content=\"&#8220;La gara per la realizzazione della metro due \u00e8 l\u2019avvio concreto di questa importante infrastruttura trasportistica di livello regionale e della pi\u00f9 grande opera di riqualificazione e di sviluppo dell\u2019area nord della citt\u00e0 di Torino. &#8220;Ho chiesto la convocazione in seduta congiunta delleCommissioni Trasporti regionale e comunale proprio per sottolinearne la valenza regionale, con finanziamento [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"\/web\/2025\/04\/14\/metro-due-parte-la-piu-grande-opera-infrastrutturale-dellarea-metropolitana\/\" \/>\n<meta property=\"og:site_name\" content=\"Partito Democratico\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-14T10:44:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-14T10:44:31+00:00\" \/>\n<meta name=\"author\" content=\"mastrodicasa\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"mastrodicasa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"\/web\/2025\/04\/14\/metro-due-parte-la-piu-grande-opera-infrastrutturale-dellarea-metropolitana\/\",\"url\":\"\/web\/2025\/04\/14\/metro-due-parte-la-piu-grande-opera-infrastrutturale-dellarea-metropolitana\/\",\"name\":\"METRO DUE: PARTE LA PI\u00d9 GRANDE OPERA INFRASTRUTTURALE DELL\u2019AREA METROPOLITANA - Partito Democratico\",\"isPartOf\":{\"@id\":\"\/web\/#website\"},\"datePublished\":\"2025-04-14T10:44:28+00:00\",\"dateModified\":\"2025-04-14T10:44:31+00:00\",\"author\":{\"@id\":\"\/web\/#\/schema\/person\/e3213afc750e7648b3ad0561ab389690\"},\"breadcrumb\":{\"@id\":\"\/web\/2025\/04\/14\/metro-due-parte-la-piu-grande-opera-infrastrutturale-dellarea-metropolitana\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"\/web\/2025\/04\/14\/metro-due-parte-la-piu-grande-opera-infrastrutturale-dellarea-metropolitana\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"\/web\/2025\/04\/14\/metro-due-parte-la-piu-grande-opera-infrastrutturale-dellarea-metropolitana\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"METRO DUE: PARTE LA PI\u00d9 GRANDE OPERA INFRASTRUTTURALE DELL\u2019AREA METROPOLITANA\"}]},{\"@type\":\"WebSite\",\"@id\":\"\/web\/#website\",\"url\":\"\/web\/\",\"name\":\"Partito Democratico\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"\/web\/#\/schema\/person\/e3213afc750e7648b3ad0561ab389690\",\"name\":\"mastrodicasa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"\/web\/#\/schema\/person\/image\/\",\"url\":\"http:\/\/0.gravatar.com\/avatar\/3193e7cdcf94bcc77fa1c5b0cf49f5f6?s=96&d=mm&r=g\",\"contentUrl\":\"http:\/\/0.gravatar.com\/avatar\/3193e7cdcf94bcc77fa1c5b0cf49f5f6?s=96&d=mm&r=g\",\"caption\":\"mastrodicasa\"},\"url\":\"\/web\/author\/mastrodicasa\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"METRO DUE: PARTE LA PI\u00d9 GRANDE OPERA INFRASTRUTTURALE DELL\u2019AREA METROPOLITANA - Partito Democratico","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"\/web\/2025\/04\/14\/metro-due-parte-la-piu-grande-opera-infrastrutturale-dellarea-metropolitana\/","og_locale":"it_IT","og_type":"article","og_title":"METRO DUE: PARTE LA PI\u00d9 GRANDE OPERA INFRASTRUTTURALE DELL\u2019AREA METROPOLITANA - Partito Democratico","og_description":"&#8220;La gara per la realizzazione della metro due \u00e8 l\u2019avvio concreto di questa importante infrastruttura trasportistica di livello regionale e della pi\u00f9 grande opera di riqualificazione e di sviluppo dell\u2019area nord della citt\u00e0 di Torino. &#8220;Ho chiesto la convocazione in seduta congiunta delleCommissioni Trasporti regionale e comunale proprio per sottolinearne la valenza regionale, con finanziamento [&hellip;]","og_url":"\/web\/2025\/04\/14\/metro-due-parte-la-piu-grande-opera-infrastrutturale-dellarea-metropolitana\/","og_site_name":"Partito Democratico","article_published_time":"2025-04-14T10:44:28+00:00","article_modified_time":"2025-04-14T10:44:31+00:00","author":"mastrodicasa","twitter_misc":{"Scritto da":"mastrodicasa","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"\/web\/2025\/04\/14\/metro-due-parte-la-piu-grande-opera-infrastrutturale-dellarea-metropolitana\/","url":"\/web\/2025\/04\/14\/metro-due-parte-la-piu-grande-opera-infrastrutturale-dellarea-metropolitana\/","name":"METRO DUE: PARTE LA PI\u00d9 GRANDE OPERA INFRASTRUTTURALE DELL\u2019AREA METROPOLITANA - Partito Democratico","isPartOf":{"@id":"\/web\/#website"},"datePublished":"2025-04-14T10:44:28+00:00","dateModified":"2025-04-14T10:44:31+00:00","author":{"@id":"\/web\/#\/schema\/person\/e3213afc750e7648b3ad0561ab389690"},"breadcrumb":{"@id":"\/web\/2025\/04\/14\/metro-due-parte-la-piu-grande-opera-infrastrutturale-dellarea-metropolitana\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["\/web\/2025\/04\/14\/metro-due-parte-la-piu-grande-opera-infrastrutturale-dellarea-metropolitana\/"]}]},{"@type":"BreadcrumbList","@id":"\/web\/2025\/04\/14\/metro-due-parte-la-piu-grande-opera-infrastrutturale-dellarea-metropolitana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"\/web\/"},{"@type":"ListItem","position":2,"name":"METRO DUE: PARTE LA PI\u00d9 GRANDE OPERA INFRASTRUTTURALE DELL\u2019AREA METROPOLITANA"}]},{"@type":"WebSite","@id":"\/web\/#website","url":"\/web\/","name":"Partito Democratico","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"\/web\/#\/schema\/person\/e3213afc750e7648b3ad0561ab389690","name":"mastrodicasa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"\/web\/#\/schema\/person\/image\/","url":"http:\/\/0.gravatar.com\/avatar\/3193e7cdcf94bcc77fa1c5b0cf49f5f6?s=96&d=mm&r=g","contentUrl":"http:\/\/0.gravatar.com\/avatar\/3193e7cdcf94bcc77fa1c5b0cf49f5f6?s=96&d=mm&r=g","caption":"mastrodicasa"},"url":"\/web\/author\/mastrodicasa\/"}]}},"_links":{"self":[{"href":"\/web\/wp-json\/wp\/v2\/posts\/3446"}],"collection":[{"href":"\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"\/web\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"\/web\/wp-json\/wp\/v2\/comments?post=3446"}],"version-history":[{"count":1,"href":"\/web\/wp-json\/wp\/v2\/posts\/3446\/revisions"}],"predecessor-version":[{"id":3447,"href":"\/web\/wp-json\/wp\/v2\/posts\/3446\/revisions\/3447"}],"wp:attachment":[{"href":"\/web\/wp-json\/wp\/v2\/media?parent=3446"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"\/web\/wp-json\/wp\/v2\/categories?post=3446"},{"taxonomy":"post_tag","embeddable":true,"href":"\/web\/wp-json\/wp\/v2\/tags?post=3446"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}