{"id":3275,"date":"2024-11-19T17:43:29","date_gmt":"2024-11-19T16:43:29","guid":{"rendered":"\/web\/?p=3275"},"modified":"2024-11-19T17:43:32","modified_gmt":"2024-11-19T16:43:32","slug":"ospedali-inail-nessun-finanziamento-ma-solo-progetti-valutabili","status":"publish","type":"post","link":"\/web\/2024\/11\/19\/ospedali-inail-nessun-finanziamento-ma-solo-progetti-valutabili\/","title":{"rendered":"<strong>OSPEDALI INAIL: NESSUN FINANZIAMENTO, MA SOLO PROGETTI \u201cVALUTABILI\u201d<\/strong>"},"content":{"rendered":"\n<p>\u201cNessuna vera novit\u00e0 sui nuovi ospedali, ma solo un nuovo tentativo di propaganda per nascondere il fallimento totale della Giunta Cirio sul tema dell\u2019edilizia sanitaria in questi anni. Tutti auspichiamo e lavoriamo perch\u00e9 ci siano nuovi ospedali in Piemonte, ma non li costruiremo, certamente, con le promesse\u201d dichiarano&nbsp;<strong>la Presidente del Gruppo Pd in Consiglio regionale Gianna Pentenero<\/strong>&nbsp;e il&nbsp;<strong>Segretario regionale Pd Piemonte Domenico Rossi<\/strong><\/p>\n\n\n\n<p>\u201cLa Commissione \u00e8 stata utile per chiarire come non ci siano risorse stanziate per il Piemonte, ma un accordo per progetti \u201cvalutabili\u201d, come dicono con chiarezza sia il DPCM sia l\u2019accordo stato-regioni. I progetti valutabili sono aumentati, ma siamo lontani dall\u2019approvazione. E la procedura \u00e8 esattamente quella che ha portato a non avviare nessun progetto non solo in Piemonte, ma anche nelle altre Regioni. Inail valuter\u00e0 i progetti, ma la risposta potrebbe essere negativa. Il rischio finanziario sui progetti resta tutto in capo alla Regione, che potrebbe ritrovarsi con tanti progetti e nessuna nuova opera\u201d proseguono gli&nbsp;<strong>esponenti dem<\/strong>.<\/p>\n\n\n\n<p>\u201cNon \u00e8 stato spiegato in nessun modo quali sono le motivazioni per cui le cose cambieranno in meglio nei prossimi anni rispetto all\u2019 inattivit\u00e0 della scorsa legislatura. Cos\u00ec come non \u00e8 chiaro con quali parametri Inail valuter\u00e0 i progetti. Inoltre, altre domande restano aperte: c\u2019\u00e8 anche la solidit\u00e0 finanziaria dell\u2019ente richiedente? Perch\u00e9 per il Piemonte, qualora dovessero partire tutte le opere, si parla di una rata complessiva di almeno 150- 200 milioni di euro di euro. La decisione di virare su INAIL come potenziale finanziatore principale avrebbe potuto coincidere con la volont\u00e0 di mettere in campo una stazione unica appaltante regionale sulle progettazioni cos\u00ec da garantire massima competenza senza scaricare sulle singole ASL le potenziali criticit\u00e0\u201d aggiungono&nbsp;<strong>Pentenero&nbsp;<\/strong>e&nbsp;<strong>Rossi.<\/strong><\/p>\n\n\n\n<p>\u201cInail ha individuato 2,250 mld di progetti finanziabili in Piemonte, ma non ne ha ancora finanziato nessuno \u2013 interviene il&nbsp;<strong>Vicepresidente della Commissione Sanit\u00e0 Daniele Valle<\/strong>&nbsp;&#8211; Se \u00e8 vero che queste risorse non incidono sulla capacit\u00e0 di indebitamento della Regione Piemonte, \u00e8 vero anche che \u2013 restituendole in 20 anni al 4% annuo \u2013 si arriverebbe a pagare circa 120 milioni di euro all\u2019anno di canoni (che sia aggiungerebbero a quelli dei PPP di Torino e Novara). Siamo preoccupati che queste risorse possano comportare una riduzione della nostra capacit\u00e0 di garantire la nostra offerta di servizi sanitari. E siamo altrettanto preoccupati che Inail possa considerarci non in grado di far fronte alla restituzione di tutto il plafond. Inail far\u00e0 da stazione appaltante di tutti gli ospedali e, ci informa l\u2019assessore, sta costituendo unit\u00e0 locali per seguire le gare. Siamo preoccupati che, in caso di via libera gli ospedali piemontesi, una nuova struttura locale di INAIL possa partire da zero per seguire 8 appalti cos\u00ec complessi: occorre che SCR e Azienda Zero trovino un ruolo e un coinvolgimento\u201d.<\/p>\n\n\n\n<p>\u201cFinalmente si \u00e8 fatta chiarezza \u2013 afferma il&nbsp;<strong>Vicepresidente del Consiglio regionale Domenico Ravetti<\/strong>&nbsp;&#8211;&nbsp;&nbsp;Questa mattina&nbsp;nella seduta congiunta delle Commissioni Bilancio e Sanit\u00e0 l\u2019assessore Federico Riboldi ha precisato che i costi per la progettazione per tutti i nuovi ospedali finanziabili con i fondi Inail (compresi i nuovi presidi di Alessandria e Cuneo) \u00e8 complessivamente di 73 milioni di euro, e che tali risorse non verranno anticipate da nessuno, ma dovranno essere reperite dalla Regione Piemonte. Pertanto, l\u2019assessore Riboldi ha smentito non solo alcuni suoi \u201cvirgolettati\u201d riportati sui giornali, ma anche quanto affermato in Commissione il 22 ottobre, ovvero che&nbsp;<em>\u201cnon abbiamo bisogno di risorse aggiuntive per Cuneo ed Alessandria, per la progettazione degli ospedali\u201d<\/em>, in quanto tali risorse sarebbero disposte dal MEF. Evidentemente, aveva ragione Cirio nel dichiarare nei giorni scorsi che le risorse in questione saranno coperte da fondi regionali. Ora si tratter\u00e0 di capire come verranno ripartite tra le diverse aziende sanitarie interessate. Se&nbsp;oggi&nbsp;si \u00e8 finalmente introdotto un elemento di linearit\u00e0 nella discussione, il merito va all\u2019insistenza del Partito democratico nel pretendere precisazioni puntuali. Avremmo tutti potuto risparmiare tempo prezioso, se la Giunta sin dall\u2019inizio avesse avuto le idee chiare sull\u2019approccio corretto per attingere ai finanziamenti Inail. Quello che \u00e8 certo \u00e8 che la storia del nuovo ospedale di Alessandria \u00e8 ancora tutta da scrivere e consiglierei all\u2019assessore Riboldi prudenza nell\u2019indicare con certezza che sar\u00e0 pronto nel 2032\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cNessuna vera novit\u00e0 sui nuovi ospedali, ma solo un nuovo tentativo di propaganda per nascondere il fallimento totale della Giunta Cirio sul tema dell\u2019edilizia sanitaria in questi anni. Tutti auspichiamo e lavoriamo perch\u00e9 ci siano nuovi ospedali in Piemonte, ma non li costruiremo, certamente, con le promesse\u201d dichiarano&nbsp;la Presidente del Gruppo Pd in Consiglio regionale [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[15,23,46],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.12 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>OSPEDALI INAIL: NESSUN FINANZIAMENTO, MA SOLO PROGETTI \u201cVALUTABILI\u201d - Partito Democratico<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"\/web\/2024\/11\/19\/ospedali-inail-nessun-finanziamento-ma-solo-progetti-valutabili\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"OSPEDALI INAIL: NESSUN FINANZIAMENTO, MA SOLO PROGETTI \u201cVALUTABILI\u201d - Partito Democratico\" \/>\n<meta property=\"og:description\" content=\"\u201cNessuna vera novit\u00e0 sui nuovi ospedali, ma solo un nuovo tentativo di propaganda per nascondere il fallimento totale della Giunta Cirio sul tema dell\u2019edilizia sanitaria in questi anni. Tutti auspichiamo e lavoriamo perch\u00e9 ci siano nuovi ospedali in Piemonte, ma non li costruiremo, certamente, con le promesse\u201d dichiarano&nbsp;la Presidente del Gruppo Pd in Consiglio regionale [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"\/web\/2024\/11\/19\/ospedali-inail-nessun-finanziamento-ma-solo-progetti-valutabili\/\" \/>\n<meta property=\"og:site_name\" content=\"Partito Democratico\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-19T16:43:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-19T16:43:32+00:00\" \/>\n<meta name=\"author\" content=\"mastrodicasa\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"mastrodicasa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"\/web\/2024\/11\/19\/ospedali-inail-nessun-finanziamento-ma-solo-progetti-valutabili\/\",\"url\":\"\/web\/2024\/11\/19\/ospedali-inail-nessun-finanziamento-ma-solo-progetti-valutabili\/\",\"name\":\"OSPEDALI INAIL: NESSUN FINANZIAMENTO, MA SOLO PROGETTI \u201cVALUTABILI\u201d - Partito Democratico\",\"isPartOf\":{\"@id\":\"\/web\/#website\"},\"datePublished\":\"2024-11-19T16:43:29+00:00\",\"dateModified\":\"2024-11-19T16:43:32+00:00\",\"author\":{\"@id\":\"\/web\/#\/schema\/person\/e3213afc750e7648b3ad0561ab389690\"},\"breadcrumb\":{\"@id\":\"\/web\/2024\/11\/19\/ospedali-inail-nessun-finanziamento-ma-solo-progetti-valutabili\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"\/web\/2024\/11\/19\/ospedali-inail-nessun-finanziamento-ma-solo-progetti-valutabili\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"\/web\/2024\/11\/19\/ospedali-inail-nessun-finanziamento-ma-solo-progetti-valutabili\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"OSPEDALI INAIL: NESSUN FINANZIAMENTO, MA SOLO PROGETTI \u201cVALUTABILI\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"\/web\/#website\",\"url\":\"\/web\/\",\"name\":\"Partito Democratico\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"\/web\/#\/schema\/person\/e3213afc750e7648b3ad0561ab389690\",\"name\":\"mastrodicasa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"\/web\/#\/schema\/person\/image\/\",\"url\":\"http:\/\/0.gravatar.com\/avatar\/3193e7cdcf94bcc77fa1c5b0cf49f5f6?s=96&d=mm&r=g\",\"contentUrl\":\"http:\/\/0.gravatar.com\/avatar\/3193e7cdcf94bcc77fa1c5b0cf49f5f6?s=96&d=mm&r=g\",\"caption\":\"mastrodicasa\"},\"url\":\"\/web\/author\/mastrodicasa\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"OSPEDALI INAIL: NESSUN FINANZIAMENTO, MA SOLO PROGETTI \u201cVALUTABILI\u201d - Partito Democratico","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"\/web\/2024\/11\/19\/ospedali-inail-nessun-finanziamento-ma-solo-progetti-valutabili\/","og_locale":"it_IT","og_type":"article","og_title":"OSPEDALI INAIL: NESSUN FINANZIAMENTO, MA SOLO PROGETTI \u201cVALUTABILI\u201d - Partito Democratico","og_description":"\u201cNessuna vera novit\u00e0 sui nuovi ospedali, ma solo un nuovo tentativo di propaganda per nascondere il fallimento totale della Giunta Cirio sul tema dell\u2019edilizia sanitaria in questi anni. Tutti auspichiamo e lavoriamo perch\u00e9 ci siano nuovi ospedali in Piemonte, ma non li costruiremo, certamente, con le promesse\u201d dichiarano&nbsp;la Presidente del Gruppo Pd in Consiglio regionale [&hellip;]","og_url":"\/web\/2024\/11\/19\/ospedali-inail-nessun-finanziamento-ma-solo-progetti-valutabili\/","og_site_name":"Partito Democratico","article_published_time":"2024-11-19T16:43:29+00:00","article_modified_time":"2024-11-19T16:43:32+00:00","author":"mastrodicasa","twitter_misc":{"Scritto da":"mastrodicasa","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"\/web\/2024\/11\/19\/ospedali-inail-nessun-finanziamento-ma-solo-progetti-valutabili\/","url":"\/web\/2024\/11\/19\/ospedali-inail-nessun-finanziamento-ma-solo-progetti-valutabili\/","name":"OSPEDALI INAIL: NESSUN FINANZIAMENTO, MA SOLO PROGETTI \u201cVALUTABILI\u201d - Partito Democratico","isPartOf":{"@id":"\/web\/#website"},"datePublished":"2024-11-19T16:43:29+00:00","dateModified":"2024-11-19T16:43:32+00:00","author":{"@id":"\/web\/#\/schema\/person\/e3213afc750e7648b3ad0561ab389690"},"breadcrumb":{"@id":"\/web\/2024\/11\/19\/ospedali-inail-nessun-finanziamento-ma-solo-progetti-valutabili\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["\/web\/2024\/11\/19\/ospedali-inail-nessun-finanziamento-ma-solo-progetti-valutabili\/"]}]},{"@type":"BreadcrumbList","@id":"\/web\/2024\/11\/19\/ospedali-inail-nessun-finanziamento-ma-solo-progetti-valutabili\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"\/web\/"},{"@type":"ListItem","position":2,"name":"OSPEDALI INAIL: NESSUN FINANZIAMENTO, MA SOLO PROGETTI \u201cVALUTABILI\u201d"}]},{"@type":"WebSite","@id":"\/web\/#website","url":"\/web\/","name":"Partito Democratico","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"\/web\/#\/schema\/person\/e3213afc750e7648b3ad0561ab389690","name":"mastrodicasa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"\/web\/#\/schema\/person\/image\/","url":"http:\/\/0.gravatar.com\/avatar\/3193e7cdcf94bcc77fa1c5b0cf49f5f6?s=96&d=mm&r=g","contentUrl":"http:\/\/0.gravatar.com\/avatar\/3193e7cdcf94bcc77fa1c5b0cf49f5f6?s=96&d=mm&r=g","caption":"mastrodicasa"},"url":"\/web\/author\/mastrodicasa\/"}]}},"_links":{"self":[{"href":"\/web\/wp-json\/wp\/v2\/posts\/3275"}],"collection":[{"href":"\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"\/web\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"\/web\/wp-json\/wp\/v2\/comments?post=3275"}],"version-history":[{"count":2,"href":"\/web\/wp-json\/wp\/v2\/posts\/3275\/revisions"}],"predecessor-version":[{"id":3277,"href":"\/web\/wp-json\/wp\/v2\/posts\/3275\/revisions\/3277"}],"wp:attachment":[{"href":"\/web\/wp-json\/wp\/v2\/media?parent=3275"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"\/web\/wp-json\/wp\/v2\/categories?post=3275"},{"taxonomy":"post_tag","embeddable":true,"href":"\/web\/wp-json\/wp\/v2\/tags?post=3275"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}