{"id":3167,"date":"2024-09-30T12:00:26","date_gmt":"2024-09-30T10:00:26","guid":{"rendered":"\/web\/?p=3167"},"modified":"2024-09-30T12:00:29","modified_gmt":"2024-09-30T10:00:29","slug":"dopo-5-anni-di-chiacchiere-si-dica-solo-se-ce-la-volonta-politica-di-riaprire-la-linea","status":"publish","type":"post","link":"\/web\/2024\/09\/30\/dopo-5-anni-di-chiacchiere-si-dica-solo-se-ce-la-volonta-politica-di-riaprire-la-linea\/","title":{"rendered":"\u201cDopo 5 anni di chiacchiere, si dica solo se c\u2019\u00e8 la volont\u00e0 politica di riaprire la linea\u201d"},"content":{"rendered":"\n<p>\u00abUna cosa \u00e8 certa: non possiamo dire ai pendolari nella tratta Ovada-Alessandria che devono rassegnarsi a viaggiare su bus strapieni, che in taluni casi saltano le fermate per impossibilit\u00e0 di accogliere altri passeggeri. Mi auguro che l\u2019assessore Gabusi luned\u00ec ad Ovada possa dare garanzie concrete sulla riapertura della tratta ferroviaria Ovada-Alessandria. Sono anni che se ne parla. Altrove, le tratte ferroviarie sono state riattivate. Per garantire un trasporto pubblico dignitoso a lavoratori e studenti, per contrastare l\u2019uso dei mezzi privati, per valorizzare le potenzialit\u00e0 turistiche dei luoghi attraversati dai treni. Se si \u00e8 fatto altrove, si pu\u00f2 fare anche qui, basta che vi sia la volont\u00e0 politica\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abUna cosa \u00e8 certa: non possiamo dire ai pendolari nella tratta Ovada-Alessandria che devono rassegnarsi a viaggiare su bus strapieni, che in taluni casi saltano le fermate per impossibilit\u00e0 di accogliere altri passeggeri. Mi auguro che l\u2019assessore Gabusi luned\u00ec ad Ovada possa dare garanzie concrete sulla riapertura della tratta ferroviaria Ovada-Alessandria. Sono anni che se [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[60],"tags":[15],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.12 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u201cDopo 5 anni di chiacchiere, si dica solo se c\u2019\u00e8 la volont\u00e0 politica di riaprire la linea\u201d - Partito Democratico<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"\/web\/2024\/09\/30\/dopo-5-anni-di-chiacchiere-si-dica-solo-se-ce-la-volonta-politica-di-riaprire-la-linea\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u201cDopo 5 anni di chiacchiere, si dica solo se c\u2019\u00e8 la volont\u00e0 politica di riaprire la linea\u201d - Partito Democratico\" \/>\n<meta property=\"og:description\" content=\"\u00abUna cosa \u00e8 certa: non possiamo dire ai pendolari nella tratta Ovada-Alessandria che devono rassegnarsi a viaggiare su bus strapieni, che in taluni casi saltano le fermate per impossibilit\u00e0 di accogliere altri passeggeri. Mi auguro che l\u2019assessore Gabusi luned\u00ec ad Ovada possa dare garanzie concrete sulla riapertura della tratta ferroviaria Ovada-Alessandria. Sono anni che se [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"\/web\/2024\/09\/30\/dopo-5-anni-di-chiacchiere-si-dica-solo-se-ce-la-volonta-politica-di-riaprire-la-linea\/\" \/>\n<meta property=\"og:site_name\" content=\"Partito Democratico\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-30T10:00:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-30T10:00:29+00:00\" \/>\n<meta name=\"author\" content=\"mastrodicasa\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"mastrodicasa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"\/web\/2024\/09\/30\/dopo-5-anni-di-chiacchiere-si-dica-solo-se-ce-la-volonta-politica-di-riaprire-la-linea\/\",\"url\":\"\/web\/2024\/09\/30\/dopo-5-anni-di-chiacchiere-si-dica-solo-se-ce-la-volonta-politica-di-riaprire-la-linea\/\",\"name\":\"\u201cDopo 5 anni di chiacchiere, si dica solo se c\u2019\u00e8 la volont\u00e0 politica di riaprire la linea\u201d - Partito Democratico\",\"isPartOf\":{\"@id\":\"\/web\/#website\"},\"datePublished\":\"2024-09-30T10:00:26+00:00\",\"dateModified\":\"2024-09-30T10:00:29+00:00\",\"author\":{\"@id\":\"\/web\/#\/schema\/person\/e3213afc750e7648b3ad0561ab389690\"},\"breadcrumb\":{\"@id\":\"\/web\/2024\/09\/30\/dopo-5-anni-di-chiacchiere-si-dica-solo-se-ce-la-volonta-politica-di-riaprire-la-linea\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"\/web\/2024\/09\/30\/dopo-5-anni-di-chiacchiere-si-dica-solo-se-ce-la-volonta-politica-di-riaprire-la-linea\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"\/web\/2024\/09\/30\/dopo-5-anni-di-chiacchiere-si-dica-solo-se-ce-la-volonta-politica-di-riaprire-la-linea\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u201cDopo 5 anni di chiacchiere, si dica solo se c\u2019\u00e8 la volont\u00e0 politica di riaprire la linea\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"\/web\/#website\",\"url\":\"\/web\/\",\"name\":\"Partito Democratico\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"\/web\/#\/schema\/person\/e3213afc750e7648b3ad0561ab389690\",\"name\":\"mastrodicasa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"\/web\/#\/schema\/person\/image\/\",\"url\":\"http:\/\/0.gravatar.com\/avatar\/3193e7cdcf94bcc77fa1c5b0cf49f5f6?s=96&d=mm&r=g\",\"contentUrl\":\"http:\/\/0.gravatar.com\/avatar\/3193e7cdcf94bcc77fa1c5b0cf49f5f6?s=96&d=mm&r=g\",\"caption\":\"mastrodicasa\"},\"url\":\"\/web\/author\/mastrodicasa\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u201cDopo 5 anni di chiacchiere, si dica solo se c\u2019\u00e8 la volont\u00e0 politica di riaprire la linea\u201d - Partito Democratico","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"\/web\/2024\/09\/30\/dopo-5-anni-di-chiacchiere-si-dica-solo-se-ce-la-volonta-politica-di-riaprire-la-linea\/","og_locale":"it_IT","og_type":"article","og_title":"\u201cDopo 5 anni di chiacchiere, si dica solo se c\u2019\u00e8 la volont\u00e0 politica di riaprire la linea\u201d - Partito Democratico","og_description":"\u00abUna cosa \u00e8 certa: non possiamo dire ai pendolari nella tratta Ovada-Alessandria che devono rassegnarsi a viaggiare su bus strapieni, che in taluni casi saltano le fermate per impossibilit\u00e0 di accogliere altri passeggeri. Mi auguro che l\u2019assessore Gabusi luned\u00ec ad Ovada possa dare garanzie concrete sulla riapertura della tratta ferroviaria Ovada-Alessandria. Sono anni che se [&hellip;]","og_url":"\/web\/2024\/09\/30\/dopo-5-anni-di-chiacchiere-si-dica-solo-se-ce-la-volonta-politica-di-riaprire-la-linea\/","og_site_name":"Partito Democratico","article_published_time":"2024-09-30T10:00:26+00:00","article_modified_time":"2024-09-30T10:00:29+00:00","author":"mastrodicasa","twitter_misc":{"Scritto da":"mastrodicasa","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"\/web\/2024\/09\/30\/dopo-5-anni-di-chiacchiere-si-dica-solo-se-ce-la-volonta-politica-di-riaprire-la-linea\/","url":"\/web\/2024\/09\/30\/dopo-5-anni-di-chiacchiere-si-dica-solo-se-ce-la-volonta-politica-di-riaprire-la-linea\/","name":"\u201cDopo 5 anni di chiacchiere, si dica solo se c\u2019\u00e8 la volont\u00e0 politica di riaprire la linea\u201d - Partito Democratico","isPartOf":{"@id":"\/web\/#website"},"datePublished":"2024-09-30T10:00:26+00:00","dateModified":"2024-09-30T10:00:29+00:00","author":{"@id":"\/web\/#\/schema\/person\/e3213afc750e7648b3ad0561ab389690"},"breadcrumb":{"@id":"\/web\/2024\/09\/30\/dopo-5-anni-di-chiacchiere-si-dica-solo-se-ce-la-volonta-politica-di-riaprire-la-linea\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["\/web\/2024\/09\/30\/dopo-5-anni-di-chiacchiere-si-dica-solo-se-ce-la-volonta-politica-di-riaprire-la-linea\/"]}]},{"@type":"BreadcrumbList","@id":"\/web\/2024\/09\/30\/dopo-5-anni-di-chiacchiere-si-dica-solo-se-ce-la-volonta-politica-di-riaprire-la-linea\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"\/web\/"},{"@type":"ListItem","position":2,"name":"\u201cDopo 5 anni di chiacchiere, si dica solo se c\u2019\u00e8 la volont\u00e0 politica di riaprire la linea\u201d"}]},{"@type":"WebSite","@id":"\/web\/#website","url":"\/web\/","name":"Partito Democratico","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"\/web\/#\/schema\/person\/e3213afc750e7648b3ad0561ab389690","name":"mastrodicasa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"\/web\/#\/schema\/person\/image\/","url":"http:\/\/0.gravatar.com\/avatar\/3193e7cdcf94bcc77fa1c5b0cf49f5f6?s=96&d=mm&r=g","contentUrl":"http:\/\/0.gravatar.com\/avatar\/3193e7cdcf94bcc77fa1c5b0cf49f5f6?s=96&d=mm&r=g","caption":"mastrodicasa"},"url":"\/web\/author\/mastrodicasa\/"}]}},"_links":{"self":[{"href":"\/web\/wp-json\/wp\/v2\/posts\/3167"}],"collection":[{"href":"\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"\/web\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"\/web\/wp-json\/wp\/v2\/comments?post=3167"}],"version-history":[{"count":1,"href":"\/web\/wp-json\/wp\/v2\/posts\/3167\/revisions"}],"predecessor-version":[{"id":3168,"href":"\/web\/wp-json\/wp\/v2\/posts\/3167\/revisions\/3168"}],"wp:attachment":[{"href":"\/web\/wp-json\/wp\/v2\/media?parent=3167"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"\/web\/wp-json\/wp\/v2\/categories?post=3167"},{"taxonomy":"post_tag","embeddable":true,"href":"\/web\/wp-json\/wp\/v2\/tags?post=3167"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}