{"id":2799,"date":"2021-07-22T10:21:55","date_gmt":"2021-07-22T08:21:55","guid":{"rendered":"\/web\/?p=2799"},"modified":"2021-07-22T10:21:58","modified_gmt":"2021-07-22T08:21:58","slug":"il-23-dei-posti-letto-e-vuoto-cosa-aspetta-la-giunta-cirio-ad-inserire-nuove-persone-in-convenzione","status":"publish","type":"post","link":"\/web\/2021\/07\/22\/il-23-dei-posti-letto-e-vuoto-cosa-aspetta-la-giunta-cirio-ad-inserire-nuove-persone-in-convenzione\/","title":{"rendered":"IL 23% DEI POSTI LETTO \u00c8 VUOTO. COSA ASPETTA LA GIUNTA CIRIO AD INSERIRE NUOVE PERSONE IN CONVENZIONE?"},"content":{"rendered":"\n<p>\u00ab<strong>Al 31 maggio, sui 30.123 posti letto accreditati dalla sanit\u00e0 piemontese, solo il 77% risultava occupato. Ci sono cio\u00e8 6.627 posti vuoti.<\/strong><\/p>\n\n\n\n<p>Questa \u00e8 l\u2019allarmante risposta al mio ultimo accesso agli atti,&nbsp;<strong>che rende concreto il pericolo di chiusura di un alto numero di Rsa del nostro territorio.<\/strong><\/p>\n\n\n\n<p>Entro fine anno potrebbe chiudere un terzo dei posti letto e le ragioni sono essenzialmente due:&nbsp;<strong>carenza di infermieri e lentezza dei nuovi inserimenti in convenzione.&nbsp;<\/strong>&nbsp;<\/p>\n\n\n\n<p>Nel 2020 la Giunta Cirio ha speso soltanto&nbsp;238 milioni di euro per le convenzioni in Rsa, cio\u00e8 per il pagamento di met\u00e0 della retta sostenuta dalle famiglie. Ben meno dei 249 milioni spesi nel 2019 e nel 2018.&nbsp;Un dato stridente se si pensa che a febbraio 2021 c\u2019erano 8.000 persone in lista d\u2019attesa per un progetto residenziale, gi\u00e0 dichiarate non autosufficienti dalle UVG delle ASL.<\/p>\n\n\n\n<p><strong>Se la Giunta regionale vuole evitare il tracollo del sistema socio-sanitario, con la chiusura di centinaia delle Rsa pi\u00f9 piccole e legate al territorio, e la conseguente ospedalizzazione inappropriata dei loro ospiti, non pu\u00f2 limitarsi a distaccare personale dal pubblico al privato e a erogare tardivi ed insufficienti ristori.&nbsp;<\/strong><strong><\/strong><\/p>\n\n\n\n<p>Poter disporre di un numero soddisfacente di lavoratori \u00e8 necessario anche per evitare ogni forma di contenzione. Occorre avviare una ricerca di infermieri negli altri Paesi europei e nel Regno Unito, e soprattutto prendere in considerazione l\u2019abolizione del numero chiuso o l\u2019estensione del numero di posti nei corsi di formazione per infermieri.&nbsp;<\/p>\n\n\n\n<p>Le Rsa sono enti privati, ma essendo autorizzati dalle ASL ed operando in molti casi in regime di convenzione,&nbsp;devono essere considerate a tutti gli effetti concessionari di pubblico servizio, finanziati dal Fondo Sanitario Regionale.&nbsp;<strong>La Giunta Cirio non pu\u00f2 assistere passivamente alla scomparsa dei servizi sul territorio, ma deve garantirne la sopravvivenza, adoperandosi per uscire dalla paralisi dei nuovi convenzionamenti e dalla penuria di infermieri.&nbsp;<\/strong>\u00c8 &nbsp;un dovere nei confronti dei numerosi anziani, spesso non autosufficienti, della nostra Regione, delle loro famiglie e anche delle migliaia di lavoratori che nelle Rsa sono impiegati.<\/p>\n\n\n\n<p><strong>Non c\u2019\u00e8 pi\u00f9 tempo: l\u2019Assessore Icardi dia un segnale!<\/strong><strong>\u00bb<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abAl 31 maggio, sui 30.123 posti letto accreditati dalla sanit\u00e0 piemontese, solo il 77% risultava occupato. Ci sono cio\u00e8 6.627 posti vuoti. Questa \u00e8 l\u2019allarmante risposta al mio ultimo accesso agli atti,&nbsp;che rende concreto il pericolo di chiusura di un alto numero di Rsa del nostro territorio. Entro fine anno potrebbe chiudere un terzo dei [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":2800,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.12 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>IL 23% DEI POSTI LETTO \u00c8 VUOTO. COSA ASPETTA LA GIUNTA CIRIO AD INSERIRE NUOVE PERSONE IN CONVENZIONE? - Partito Democratico<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"\/web\/2021\/07\/22\/il-23-dei-posti-letto-e-vuoto-cosa-aspetta-la-giunta-cirio-ad-inserire-nuove-persone-in-convenzione\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"IL 23% DEI POSTI LETTO \u00c8 VUOTO. COSA ASPETTA LA GIUNTA CIRIO AD INSERIRE NUOVE PERSONE IN CONVENZIONE? - Partito Democratico\" \/>\n<meta property=\"og:description\" content=\"\u00abAl 31 maggio, sui 30.123 posti letto accreditati dalla sanit\u00e0 piemontese, solo il 77% risultava occupato. Ci sono cio\u00e8 6.627 posti vuoti. Questa \u00e8 l\u2019allarmante risposta al mio ultimo accesso agli atti,&nbsp;che rende concreto il pericolo di chiusura di un alto numero di Rsa del nostro territorio. Entro fine anno potrebbe chiudere un terzo dei [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"\/web\/2021\/07\/22\/il-23-dei-posti-letto-e-vuoto-cosa-aspetta-la-giunta-cirio-ad-inserire-nuove-persone-in-convenzione\/\" \/>\n<meta property=\"og:site_name\" content=\"Partito Democratico\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-22T08:21:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-07-22T08:21:58+00:00\" \/>\n<meta property=\"og:image\" content=\"\/web\/wp-content\/uploads\/sites\/8\/2021\/07\/Anziani-RSA.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"563\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mastrodicasa\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"mastrodicasa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"\/web\/2021\/07\/22\/il-23-dei-posti-letto-e-vuoto-cosa-aspetta-la-giunta-cirio-ad-inserire-nuove-persone-in-convenzione\/\",\"url\":\"\/web\/2021\/07\/22\/il-23-dei-posti-letto-e-vuoto-cosa-aspetta-la-giunta-cirio-ad-inserire-nuove-persone-in-convenzione\/\",\"name\":\"IL 23% DEI POSTI LETTO \u00c8 VUOTO. COSA ASPETTA LA GIUNTA CIRIO AD INSERIRE NUOVE PERSONE IN CONVENZIONE? - Partito Democratico\",\"isPartOf\":{\"@id\":\"\/web\/#website\"},\"datePublished\":\"2021-07-22T08:21:55+00:00\",\"dateModified\":\"2021-07-22T08:21:58+00:00\",\"author\":{\"@id\":\"\/web\/#\/schema\/person\/e3213afc750e7648b3ad0561ab389690\"},\"breadcrumb\":{\"@id\":\"\/web\/2021\/07\/22\/il-23-dei-posti-letto-e-vuoto-cosa-aspetta-la-giunta-cirio-ad-inserire-nuove-persone-in-convenzione\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"\/web\/2021\/07\/22\/il-23-dei-posti-letto-e-vuoto-cosa-aspetta-la-giunta-cirio-ad-inserire-nuove-persone-in-convenzione\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"\/web\/2021\/07\/22\/il-23-dei-posti-letto-e-vuoto-cosa-aspetta-la-giunta-cirio-ad-inserire-nuove-persone-in-convenzione\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"IL 23% DEI POSTI LETTO \u00c8 VUOTO. COSA ASPETTA LA GIUNTA CIRIO AD INSERIRE NUOVE PERSONE IN CONVENZIONE?\"}]},{\"@type\":\"WebSite\",\"@id\":\"\/web\/#website\",\"url\":\"\/web\/\",\"name\":\"Partito Democratico\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"\/web\/#\/schema\/person\/e3213afc750e7648b3ad0561ab389690\",\"name\":\"mastrodicasa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"\/web\/#\/schema\/person\/image\/\",\"url\":\"http:\/\/0.gravatar.com\/avatar\/3193e7cdcf94bcc77fa1c5b0cf49f5f6?s=96&d=mm&r=g\",\"contentUrl\":\"http:\/\/0.gravatar.com\/avatar\/3193e7cdcf94bcc77fa1c5b0cf49f5f6?s=96&d=mm&r=g\",\"caption\":\"mastrodicasa\"},\"url\":\"\/web\/author\/mastrodicasa\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"IL 23% DEI POSTI LETTO \u00c8 VUOTO. COSA ASPETTA LA GIUNTA CIRIO AD INSERIRE NUOVE PERSONE IN CONVENZIONE? - Partito Democratico","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"\/web\/2021\/07\/22\/il-23-dei-posti-letto-e-vuoto-cosa-aspetta-la-giunta-cirio-ad-inserire-nuove-persone-in-convenzione\/","og_locale":"it_IT","og_type":"article","og_title":"IL 23% DEI POSTI LETTO \u00c8 VUOTO. COSA ASPETTA LA GIUNTA CIRIO AD INSERIRE NUOVE PERSONE IN CONVENZIONE? - Partito Democratico","og_description":"\u00abAl 31 maggio, sui 30.123 posti letto accreditati dalla sanit\u00e0 piemontese, solo il 77% risultava occupato. Ci sono cio\u00e8 6.627 posti vuoti. Questa \u00e8 l\u2019allarmante risposta al mio ultimo accesso agli atti,&nbsp;che rende concreto il pericolo di chiusura di un alto numero di Rsa del nostro territorio. Entro fine anno potrebbe chiudere un terzo dei [&hellip;]","og_url":"\/web\/2021\/07\/22\/il-23-dei-posti-letto-e-vuoto-cosa-aspetta-la-giunta-cirio-ad-inserire-nuove-persone-in-convenzione\/","og_site_name":"Partito Democratico","article_published_time":"2021-07-22T08:21:55+00:00","article_modified_time":"2021-07-22T08:21:58+00:00","og_image":[{"width":900,"height":563,"url":"\/web\/wp-content\/uploads\/sites\/8\/2021\/07\/Anziani-RSA.jpg","type":"image\/jpeg"}],"author":"mastrodicasa","twitter_misc":{"Scritto da":"mastrodicasa","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"\/web\/2021\/07\/22\/il-23-dei-posti-letto-e-vuoto-cosa-aspetta-la-giunta-cirio-ad-inserire-nuove-persone-in-convenzione\/","url":"\/web\/2021\/07\/22\/il-23-dei-posti-letto-e-vuoto-cosa-aspetta-la-giunta-cirio-ad-inserire-nuove-persone-in-convenzione\/","name":"IL 23% DEI POSTI LETTO \u00c8 VUOTO. COSA ASPETTA LA GIUNTA CIRIO AD INSERIRE NUOVE PERSONE IN CONVENZIONE? - Partito Democratico","isPartOf":{"@id":"\/web\/#website"},"datePublished":"2021-07-22T08:21:55+00:00","dateModified":"2021-07-22T08:21:58+00:00","author":{"@id":"\/web\/#\/schema\/person\/e3213afc750e7648b3ad0561ab389690"},"breadcrumb":{"@id":"\/web\/2021\/07\/22\/il-23-dei-posti-letto-e-vuoto-cosa-aspetta-la-giunta-cirio-ad-inserire-nuove-persone-in-convenzione\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["\/web\/2021\/07\/22\/il-23-dei-posti-letto-e-vuoto-cosa-aspetta-la-giunta-cirio-ad-inserire-nuove-persone-in-convenzione\/"]}]},{"@type":"BreadcrumbList","@id":"\/web\/2021\/07\/22\/il-23-dei-posti-letto-e-vuoto-cosa-aspetta-la-giunta-cirio-ad-inserire-nuove-persone-in-convenzione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"\/web\/"},{"@type":"ListItem","position":2,"name":"IL 23% DEI POSTI LETTO \u00c8 VUOTO. COSA ASPETTA LA GIUNTA CIRIO AD INSERIRE NUOVE PERSONE IN CONVENZIONE?"}]},{"@type":"WebSite","@id":"\/web\/#website","url":"\/web\/","name":"Partito Democratico","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"\/web\/#\/schema\/person\/e3213afc750e7648b3ad0561ab389690","name":"mastrodicasa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"\/web\/#\/schema\/person\/image\/","url":"http:\/\/0.gravatar.com\/avatar\/3193e7cdcf94bcc77fa1c5b0cf49f5f6?s=96&d=mm&r=g","contentUrl":"http:\/\/0.gravatar.com\/avatar\/3193e7cdcf94bcc77fa1c5b0cf49f5f6?s=96&d=mm&r=g","caption":"mastrodicasa"},"url":"\/web\/author\/mastrodicasa\/"}]}},"_links":{"self":[{"href":"\/web\/wp-json\/wp\/v2\/posts\/2799"}],"collection":[{"href":"\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"\/web\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"\/web\/wp-json\/wp\/v2\/comments?post=2799"}],"version-history":[{"count":1,"href":"\/web\/wp-json\/wp\/v2\/posts\/2799\/revisions"}],"predecessor-version":[{"id":2801,"href":"\/web\/wp-json\/wp\/v2\/posts\/2799\/revisions\/2801"}],"wp:featuredmedia":[{"embeddable":true,"href":"\/web\/wp-json\/wp\/v2\/media\/2800"}],"wp:attachment":[{"href":"\/web\/wp-json\/wp\/v2\/media?parent=2799"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"\/web\/wp-json\/wp\/v2\/categories?post=2799"},{"taxonomy":"post_tag","embeddable":true,"href":"\/web\/wp-json\/wp\/v2\/tags?post=2799"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}