{"id":2087,"date":"2019-12-10T14:38:26","date_gmt":"2019-12-10T13:38:26","guid":{"rendered":"\/web\/?p=2087"},"modified":"2019-12-10T14:38:28","modified_gmt":"2019-12-10T13:38:28","slug":"approvato-lodg-per-lacquisto-del-software-di-sottotitolazione-per-gli-studenti-sordi-un-altro-passo-verso-laccessibilita","status":"publish","type":"post","link":"\/web\/2019\/12\/10\/approvato-lodg-per-lacquisto-del-software-di-sottotitolazione-per-gli-studenti-sordi-un-altro-passo-verso-laccessibilita\/","title":{"rendered":"APPROVATO L\u2019ODG PER L\u2019ACQUISTO DEL SOFTWARE DI SOTTOTITOLAZIONE PER GLI STUDENTI SORDI. UN ALTRO PASSO VERSO L\u2019ACCESSIBILITA\u2019"},"content":{"rendered":"\n<p>&nbsp;\u201cSono molto soddisfatto per l\u2019approvazione, nella seduta del Consiglio regionale di oggi, dell\u2019ordine del giorno, collegato all\u2019Assestamento di Bilancio, che ho presentato insieme al collega Marrone, che impegna la Giunta a prevedere uno stanziamento di risorse per acquistare nel 2020 il programma \u201cDragon NaturallySpeaking\u201d, un software di sottotitolazione automatica per gli studenti sordi dell\u2019Universit\u00e0 di Torino e ad attivare un servizio di sottotitolazione delle sedute del Consiglio regionale\u201d afferma il vicepresidente della Commissione Cultura del Consiglio regionale&nbsp;<strong>Daniele Valle<\/strong>.<\/p>\n\n\n\n<p>\u201cAbbiamo accolto alcune settimane fa l\u2019appello di una studentessa sorda dell\u2019Universit\u00e0 di Torino che ha chiesto il riconoscimento della lingua dei segni anche a livello parlamentare e ha spiegato che le otto ore di interprete a lei assegnate dall\u2019Universit\u00e0, purtroppo, non sono sufficienti a coprire quelle delle lezioni che deve seguire per laurearsi e ci siamo impegnati a rendere lo studio universitario e le Istituzioni accessibili a tutti\u201d prosegue&nbsp;<strong>Valle<\/strong>.<\/p>\n\n\n\n<p>\u201cCon l\u2019approvazione di questo atto di indirizzo \u00e8 stato mantenuto un impegno nei confronti di tutti i ragazzi sordi ai quali le Istituzioni devono garantire il diritto allo studio e a potersi laureare negli stessi tempi dei loro colleghi\u201d conclude&nbsp;<strong>Valle<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp;\u201cSono molto soddisfatto per l\u2019approvazione, nella seduta del Consiglio regionale di oggi, dell\u2019ordine del giorno, collegato all\u2019Assestamento di Bilancio, che ho presentato insieme al collega Marrone, che impegna la Giunta a prevedere uno stanziamento di risorse per acquistare nel 2020 il programma \u201cDragon NaturallySpeaking\u201d, un software di sottotitolazione automatica per gli studenti sordi dell\u2019Universit\u00e0 di [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":2088,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[59],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.12 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>APPROVATO L\u2019ODG PER L\u2019ACQUISTO DEL SOFTWARE DI SOTTOTITOLAZIONE PER GLI STUDENTI SORDI. UN ALTRO PASSO VERSO L\u2019ACCESSIBILITA\u2019 - Partito Democratico<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"\/web\/2019\/12\/10\/approvato-lodg-per-lacquisto-del-software-di-sottotitolazione-per-gli-studenti-sordi-un-altro-passo-verso-laccessibilita\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"APPROVATO L\u2019ODG PER L\u2019ACQUISTO DEL SOFTWARE DI SOTTOTITOLAZIONE PER GLI STUDENTI SORDI. UN ALTRO PASSO VERSO L\u2019ACCESSIBILITA\u2019 - Partito Democratico\" \/>\n<meta property=\"og:description\" content=\"&nbsp;\u201cSono molto soddisfatto per l\u2019approvazione, nella seduta del Consiglio regionale di oggi, dell\u2019ordine del giorno, collegato all\u2019Assestamento di Bilancio, che ho presentato insieme al collega Marrone, che impegna la Giunta a prevedere uno stanziamento di risorse per acquistare nel 2020 il programma \u201cDragon NaturallySpeaking\u201d, un software di sottotitolazione automatica per gli studenti sordi dell\u2019Universit\u00e0 di [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"\/web\/2019\/12\/10\/approvato-lodg-per-lacquisto-del-software-di-sottotitolazione-per-gli-studenti-sordi-un-altro-passo-verso-laccessibilita\/\" \/>\n<meta property=\"og:site_name\" content=\"Partito Democratico\" \/>\n<meta property=\"article:published_time\" content=\"2019-12-10T13:38:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-12-10T13:38:28+00:00\" \/>\n<meta property=\"og:image\" content=\"\/web\/wp-content\/uploads\/sites\/8\/2019\/12\/Aggiungi-un-sottotitolo.png\" \/>\n\t<meta property=\"og:image:width\" content=\"940\" \/>\n\t<meta property=\"og:image:height\" content=\"788\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"mastrodicasa\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"mastrodicasa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"\/web\/2019\/12\/10\/approvato-lodg-per-lacquisto-del-software-di-sottotitolazione-per-gli-studenti-sordi-un-altro-passo-verso-laccessibilita\/\",\"url\":\"\/web\/2019\/12\/10\/approvato-lodg-per-lacquisto-del-software-di-sottotitolazione-per-gli-studenti-sordi-un-altro-passo-verso-laccessibilita\/\",\"name\":\"APPROVATO L\u2019ODG PER L\u2019ACQUISTO DEL SOFTWARE DI SOTTOTITOLAZIONE PER GLI STUDENTI SORDI. UN ALTRO PASSO VERSO L\u2019ACCESSIBILITA\u2019 - Partito Democratico\",\"isPartOf\":{\"@id\":\"\/web\/#website\"},\"datePublished\":\"2019-12-10T13:38:26+00:00\",\"dateModified\":\"2019-12-10T13:38:28+00:00\",\"author\":{\"@id\":\"\/web\/#\/schema\/person\/e3213afc750e7648b3ad0561ab389690\"},\"breadcrumb\":{\"@id\":\"\/web\/2019\/12\/10\/approvato-lodg-per-lacquisto-del-software-di-sottotitolazione-per-gli-studenti-sordi-un-altro-passo-verso-laccessibilita\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"\/web\/2019\/12\/10\/approvato-lodg-per-lacquisto-del-software-di-sottotitolazione-per-gli-studenti-sordi-un-altro-passo-verso-laccessibilita\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"\/web\/2019\/12\/10\/approvato-lodg-per-lacquisto-del-software-di-sottotitolazione-per-gli-studenti-sordi-un-altro-passo-verso-laccessibilita\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"APPROVATO L\u2019ODG PER L\u2019ACQUISTO DEL SOFTWARE DI SOTTOTITOLAZIONE PER GLI STUDENTI SORDI. UN ALTRO PASSO VERSO L\u2019ACCESSIBILITA\u2019\"}]},{\"@type\":\"WebSite\",\"@id\":\"\/web\/#website\",\"url\":\"\/web\/\",\"name\":\"Partito Democratico\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"\/web\/#\/schema\/person\/e3213afc750e7648b3ad0561ab389690\",\"name\":\"mastrodicasa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"\/web\/#\/schema\/person\/image\/\",\"url\":\"http:\/\/0.gravatar.com\/avatar\/3193e7cdcf94bcc77fa1c5b0cf49f5f6?s=96&d=mm&r=g\",\"contentUrl\":\"http:\/\/0.gravatar.com\/avatar\/3193e7cdcf94bcc77fa1c5b0cf49f5f6?s=96&d=mm&r=g\",\"caption\":\"mastrodicasa\"},\"url\":\"\/web\/author\/mastrodicasa\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"APPROVATO L\u2019ODG PER L\u2019ACQUISTO DEL SOFTWARE DI SOTTOTITOLAZIONE PER GLI STUDENTI SORDI. UN ALTRO PASSO VERSO L\u2019ACCESSIBILITA\u2019 - Partito Democratico","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"\/web\/2019\/12\/10\/approvato-lodg-per-lacquisto-del-software-di-sottotitolazione-per-gli-studenti-sordi-un-altro-passo-verso-laccessibilita\/","og_locale":"it_IT","og_type":"article","og_title":"APPROVATO L\u2019ODG PER L\u2019ACQUISTO DEL SOFTWARE DI SOTTOTITOLAZIONE PER GLI STUDENTI SORDI. UN ALTRO PASSO VERSO L\u2019ACCESSIBILITA\u2019 - Partito Democratico","og_description":"&nbsp;\u201cSono molto soddisfatto per l\u2019approvazione, nella seduta del Consiglio regionale di oggi, dell\u2019ordine del giorno, collegato all\u2019Assestamento di Bilancio, che ho presentato insieme al collega Marrone, che impegna la Giunta a prevedere uno stanziamento di risorse per acquistare nel 2020 il programma \u201cDragon NaturallySpeaking\u201d, un software di sottotitolazione automatica per gli studenti sordi dell\u2019Universit\u00e0 di [&hellip;]","og_url":"\/web\/2019\/12\/10\/approvato-lodg-per-lacquisto-del-software-di-sottotitolazione-per-gli-studenti-sordi-un-altro-passo-verso-laccessibilita\/","og_site_name":"Partito Democratico","article_published_time":"2019-12-10T13:38:26+00:00","article_modified_time":"2019-12-10T13:38:28+00:00","og_image":[{"width":940,"height":788,"url":"\/web\/wp-content\/uploads\/sites\/8\/2019\/12\/Aggiungi-un-sottotitolo.png","type":"image\/png"}],"author":"mastrodicasa","twitter_misc":{"Scritto da":"mastrodicasa","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"\/web\/2019\/12\/10\/approvato-lodg-per-lacquisto-del-software-di-sottotitolazione-per-gli-studenti-sordi-un-altro-passo-verso-laccessibilita\/","url":"\/web\/2019\/12\/10\/approvato-lodg-per-lacquisto-del-software-di-sottotitolazione-per-gli-studenti-sordi-un-altro-passo-verso-laccessibilita\/","name":"APPROVATO L\u2019ODG PER L\u2019ACQUISTO DEL SOFTWARE DI SOTTOTITOLAZIONE PER GLI STUDENTI SORDI. UN ALTRO PASSO VERSO L\u2019ACCESSIBILITA\u2019 - Partito Democratico","isPartOf":{"@id":"\/web\/#website"},"datePublished":"2019-12-10T13:38:26+00:00","dateModified":"2019-12-10T13:38:28+00:00","author":{"@id":"\/web\/#\/schema\/person\/e3213afc750e7648b3ad0561ab389690"},"breadcrumb":{"@id":"\/web\/2019\/12\/10\/approvato-lodg-per-lacquisto-del-software-di-sottotitolazione-per-gli-studenti-sordi-un-altro-passo-verso-laccessibilita\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["\/web\/2019\/12\/10\/approvato-lodg-per-lacquisto-del-software-di-sottotitolazione-per-gli-studenti-sordi-un-altro-passo-verso-laccessibilita\/"]}]},{"@type":"BreadcrumbList","@id":"\/web\/2019\/12\/10\/approvato-lodg-per-lacquisto-del-software-di-sottotitolazione-per-gli-studenti-sordi-un-altro-passo-verso-laccessibilita\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"\/web\/"},{"@type":"ListItem","position":2,"name":"APPROVATO L\u2019ODG PER L\u2019ACQUISTO DEL SOFTWARE DI SOTTOTITOLAZIONE PER GLI STUDENTI SORDI. UN ALTRO PASSO VERSO L\u2019ACCESSIBILITA\u2019"}]},{"@type":"WebSite","@id":"\/web\/#website","url":"\/web\/","name":"Partito Democratico","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"\/web\/#\/schema\/person\/e3213afc750e7648b3ad0561ab389690","name":"mastrodicasa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"\/web\/#\/schema\/person\/image\/","url":"http:\/\/0.gravatar.com\/avatar\/3193e7cdcf94bcc77fa1c5b0cf49f5f6?s=96&d=mm&r=g","contentUrl":"http:\/\/0.gravatar.com\/avatar\/3193e7cdcf94bcc77fa1c5b0cf49f5f6?s=96&d=mm&r=g","caption":"mastrodicasa"},"url":"\/web\/author\/mastrodicasa\/"}]}},"_links":{"self":[{"href":"\/web\/wp-json\/wp\/v2\/posts\/2087"}],"collection":[{"href":"\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"\/web\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"\/web\/wp-json\/wp\/v2\/comments?post=2087"}],"version-history":[{"count":1,"href":"\/web\/wp-json\/wp\/v2\/posts\/2087\/revisions"}],"predecessor-version":[{"id":2089,"href":"\/web\/wp-json\/wp\/v2\/posts\/2087\/revisions\/2089"}],"wp:featuredmedia":[{"embeddable":true,"href":"\/web\/wp-json\/wp\/v2\/media\/2088"}],"wp:attachment":[{"href":"\/web\/wp-json\/wp\/v2\/media?parent=2087"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"\/web\/wp-json\/wp\/v2\/categories?post=2087"},{"taxonomy":"post_tag","embeddable":true,"href":"\/web\/wp-json\/wp\/v2\/tags?post=2087"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}