{"id":1475,"date":"2016-09-19T11:52:44","date_gmt":"2016-09-19T09:52:44","guid":{"rendered":"\/web\/?p=1475"},"modified":"2016-09-19T11:52:44","modified_gmt":"2016-09-19T09:52:44","slug":"eurofidi-ai-sindacati-massimo-impegno-lavoratori-continuita-servizi","status":"publish","type":"post","link":"\/web\/2016\/09\/19\/eurofidi-ai-sindacati-massimo-impegno-lavoratori-continuita-servizi\/","title":{"rendered":"Eurofidi: ai sindacati massimo impegno per i lavoratori e per continuit\u00e0 servizi"},"content":{"rendered":"<p>Stamattina il gruppo consiliare regionale del partito democratico ha incontrato i sindacati della societ\u00e0 Eurofidi. &#8220;Bisogna agire subito, dobbiamo lavorare per mantenere operativa una delle pi\u00f9 grandi societ\u00e0 europee di sostegno al credito per le imprese&#8221;: commenta cos\u00ec il capogruppo del PD Davide Gariglio dopo l&#8217;incontro con le organizzazioni sindacali. &#8220;Dobbiamo &#8211; prosegue &#8211; tutelare le centinaia di lavoratori e l&#8217;importante lavoro svolto a sostegno delle imprese della nostra regione. Chiediamo &#8211; rimarca Gariglio &#8211; che l&#8217;Assessore allo sviluppo economico De Santis illustri nella prossima seduta di Consiglio regionale le intenzioni della regione Piemonte, proprio in qualit\u00e0 di socio della societ\u00e0 e chiederemo agli amministratori della stessa di venire in Commissione. Non possiamo rassegnarci al peggio &#8211; conclude &#8211; \u00a0pur nella complessit\u00e0 della situazione dobbiamo concentrarci per la tutela dei lavoratori e dei servizi erogati&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Stamattina il gruppo consiliare regionale del partito democratico ha incontrato i sindacati della societ\u00e0 Eurofidi. &#8220;Bisogna agire subito, dobbiamo lavorare per mantenere operativa una delle pi\u00f9 grandi societ\u00e0 europee di sostegno al credito per le imprese&#8221;: commenta cos\u00ec il capogruppo del PD Davide Gariglio dopo l&#8217;incontro con le organizzazioni sindacali. &#8220;Dobbiamo &#8211; prosegue &#8211; tutelare [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":909,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[21],"tags":[19],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.12 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Eurofidi: ai sindacati massimo impegno per i lavoratori e per continuit\u00e0 servizi - Partito Democratico<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"\/web\/2016\/09\/19\/eurofidi-ai-sindacati-massimo-impegno-lavoratori-continuita-servizi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Eurofidi: ai sindacati massimo impegno per i lavoratori e per continuit\u00e0 servizi - Partito Democratico\" \/>\n<meta property=\"og:description\" content=\"Stamattina il gruppo consiliare regionale del partito democratico ha incontrato i sindacati della societ\u00e0 Eurofidi. &#8220;Bisogna agire subito, dobbiamo lavorare per mantenere operativa una delle pi\u00f9 grandi societ\u00e0 europee di sostegno al credito per le imprese&#8221;: commenta cos\u00ec il capogruppo del PD Davide Gariglio dopo l&#8217;incontro con le organizzazioni sindacali. &#8220;Dobbiamo &#8211; prosegue &#8211; tutelare [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"\/web\/2016\/09\/19\/eurofidi-ai-sindacati-massimo-impegno-lavoratori-continuita-servizi\/\" \/>\n<meta property=\"og:site_name\" content=\"Partito Democratico\" \/>\n<meta property=\"article:published_time\" content=\"2016-09-19T09:52:44+00:00\" \/>\n<meta property=\"og:image\" content=\"\/web\/wp-content\/uploads\/sites\/8\/2015\/09\/trovare-lavoro1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1675\" \/>\n\t<meta property=\"og:image:height\" content=\"1135\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mastrodicasa\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"mastrodicasa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"\/web\/2016\/09\/19\/eurofidi-ai-sindacati-massimo-impegno-lavoratori-continuita-servizi\/\",\"url\":\"\/web\/2016\/09\/19\/eurofidi-ai-sindacati-massimo-impegno-lavoratori-continuita-servizi\/\",\"name\":\"Eurofidi: ai sindacati massimo impegno per i lavoratori e per continuit\u00e0 servizi - Partito Democratico\",\"isPartOf\":{\"@id\":\"\/web\/#website\"},\"datePublished\":\"2016-09-19T09:52:44+00:00\",\"dateModified\":\"2016-09-19T09:52:44+00:00\",\"author\":{\"@id\":\"\/web\/#\/schema\/person\/e3213afc750e7648b3ad0561ab389690\"},\"breadcrumb\":{\"@id\":\"\/web\/2016\/09\/19\/eurofidi-ai-sindacati-massimo-impegno-lavoratori-continuita-servizi\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"\/web\/2016\/09\/19\/eurofidi-ai-sindacati-massimo-impegno-lavoratori-continuita-servizi\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"\/web\/2016\/09\/19\/eurofidi-ai-sindacati-massimo-impegno-lavoratori-continuita-servizi\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eurofidi: ai sindacati massimo impegno per i lavoratori e per continuit\u00e0 servizi\"}]},{\"@type\":\"WebSite\",\"@id\":\"\/web\/#website\",\"url\":\"\/web\/\",\"name\":\"Partito Democratico\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"\/web\/#\/schema\/person\/e3213afc750e7648b3ad0561ab389690\",\"name\":\"mastrodicasa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"\/web\/#\/schema\/person\/image\/\",\"url\":\"http:\/\/0.gravatar.com\/avatar\/3193e7cdcf94bcc77fa1c5b0cf49f5f6?s=96&d=mm&r=g\",\"contentUrl\":\"http:\/\/0.gravatar.com\/avatar\/3193e7cdcf94bcc77fa1c5b0cf49f5f6?s=96&d=mm&r=g\",\"caption\":\"mastrodicasa\"},\"url\":\"\/web\/author\/mastrodicasa\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Eurofidi: ai sindacati massimo impegno per i lavoratori e per continuit\u00e0 servizi - Partito Democratico","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"\/web\/2016\/09\/19\/eurofidi-ai-sindacati-massimo-impegno-lavoratori-continuita-servizi\/","og_locale":"it_IT","og_type":"article","og_title":"Eurofidi: ai sindacati massimo impegno per i lavoratori e per continuit\u00e0 servizi - Partito Democratico","og_description":"Stamattina il gruppo consiliare regionale del partito democratico ha incontrato i sindacati della societ\u00e0 Eurofidi. &#8220;Bisogna agire subito, dobbiamo lavorare per mantenere operativa una delle pi\u00f9 grandi societ\u00e0 europee di sostegno al credito per le imprese&#8221;: commenta cos\u00ec il capogruppo del PD Davide Gariglio dopo l&#8217;incontro con le organizzazioni sindacali. &#8220;Dobbiamo &#8211; prosegue &#8211; tutelare [&hellip;]","og_url":"\/web\/2016\/09\/19\/eurofidi-ai-sindacati-massimo-impegno-lavoratori-continuita-servizi\/","og_site_name":"Partito Democratico","article_published_time":"2016-09-19T09:52:44+00:00","og_image":[{"width":1675,"height":1135,"url":"\/web\/wp-content\/uploads\/sites\/8\/2015\/09\/trovare-lavoro1.jpg","type":"image\/jpeg"}],"author":"mastrodicasa","twitter_misc":{"Scritto da":"mastrodicasa","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"\/web\/2016\/09\/19\/eurofidi-ai-sindacati-massimo-impegno-lavoratori-continuita-servizi\/","url":"\/web\/2016\/09\/19\/eurofidi-ai-sindacati-massimo-impegno-lavoratori-continuita-servizi\/","name":"Eurofidi: ai sindacati massimo impegno per i lavoratori e per continuit\u00e0 servizi - Partito Democratico","isPartOf":{"@id":"\/web\/#website"},"datePublished":"2016-09-19T09:52:44+00:00","dateModified":"2016-09-19T09:52:44+00:00","author":{"@id":"\/web\/#\/schema\/person\/e3213afc750e7648b3ad0561ab389690"},"breadcrumb":{"@id":"\/web\/2016\/09\/19\/eurofidi-ai-sindacati-massimo-impegno-lavoratori-continuita-servizi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["\/web\/2016\/09\/19\/eurofidi-ai-sindacati-massimo-impegno-lavoratori-continuita-servizi\/"]}]},{"@type":"BreadcrumbList","@id":"\/web\/2016\/09\/19\/eurofidi-ai-sindacati-massimo-impegno-lavoratori-continuita-servizi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"\/web\/"},{"@type":"ListItem","position":2,"name":"Eurofidi: ai sindacati massimo impegno per i lavoratori e per continuit\u00e0 servizi"}]},{"@type":"WebSite","@id":"\/web\/#website","url":"\/web\/","name":"Partito Democratico","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"\/web\/#\/schema\/person\/e3213afc750e7648b3ad0561ab389690","name":"mastrodicasa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"\/web\/#\/schema\/person\/image\/","url":"http:\/\/0.gravatar.com\/avatar\/3193e7cdcf94bcc77fa1c5b0cf49f5f6?s=96&d=mm&r=g","contentUrl":"http:\/\/0.gravatar.com\/avatar\/3193e7cdcf94bcc77fa1c5b0cf49f5f6?s=96&d=mm&r=g","caption":"mastrodicasa"},"url":"\/web\/author\/mastrodicasa\/"}]}},"_links":{"self":[{"href":"\/web\/wp-json\/wp\/v2\/posts\/1475"}],"collection":[{"href":"\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"\/web\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"\/web\/wp-json\/wp\/v2\/comments?post=1475"}],"version-history":[{"count":1,"href":"\/web\/wp-json\/wp\/v2\/posts\/1475\/revisions"}],"predecessor-version":[{"id":1476,"href":"\/web\/wp-json\/wp\/v2\/posts\/1475\/revisions\/1476"}],"wp:featuredmedia":[{"embeddable":true,"href":"\/web\/wp-json\/wp\/v2\/media\/909"}],"wp:attachment":[{"href":"\/web\/wp-json\/wp\/v2\/media?parent=1475"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"\/web\/wp-json\/wp\/v2\/categories?post=1475"},{"taxonomy":"post_tag","embeddable":true,"href":"\/web\/wp-json\/wp\/v2\/tags?post=1475"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}