{"id":1305,"date":"2016-03-31T11:53:02","date_gmt":"2016-03-31T09:53:02","guid":{"rendered":"\/web\/?p=1305"},"modified":"2016-03-31T11:53:48","modified_gmt":"2016-03-31T09:53:48","slug":"1305","status":"publish","type":"post","link":"\/web\/2016\/03\/31\/1305\/","title":{"rendered":"Linee guida per l\u2019erogazione di prestazioni odontoiatriche nell\u2019ambito del Servizio sanitario pubblico"},"content":{"rendered":"<p><strong><em>Ordine del giorno di Paolo Allemano: Linee guida per l\u2019erogazione di prestazioni odontoiatriche in regime di extra LEA nell\u2019ambito del Servizio sanitario pubblico<\/em><\/strong><\/p>\n<h2><em>Il Consiglio regionale del Piemonte,\u00a0<\/em>premesso che<\/h2>\n<ul>\n<li>il ruolo dell\u2019Odontoiatria all\u2019interno del Sistema Sanitario Nazionale (SSN) \u00e8 al centro di una annosa controversa. Infatti l\u2019Odontoiatria fatica a trovare una corretta collocazione nell\u2019ambito della Sanit\u00e0 pubblica con una graduale riduzione, nel corso degli anni, delle prestazioni erogate nell\u2019ambito dei Livelli essenziali di assistenza (LEA). Le cause sono molteplici, prima tra tutte il forte impatto economico che l\u2019eventuale erogazione universalistica delle prestazioni odontoiatriche determinerebbe a carico dei bilanci pubblici;<\/li>\n<li>per questi motivi l\u2019assistenza odontoiatrica rappresenta il settore in cui il Settore Sanitario Nazionale (SSN) ha profuso un impegno limitato dal punto di vista dei servizi offerti, dei potenziali miglioramenti della qualit\u00e0 di vita e della sostenibilit\u00e0 economica per i singoli e per la collettivit\u00e0;<\/li>\n<li>tali problematiche, tuttavia, non costituiscono una peculiarit\u00e0 del nostro SSN, ma sono comuni anche a molti altri Servizi sanitari, inclusi quelli basati su sistemi di assicurazione sociale. Nondimeno la quantit\u00e0 di prestazioni erogate nel settore pubblico vede il SSN italiano tra i pi\u00f9 bassi in Europa con 0,6 visite per abitante all\u2019anno, a fronte di 1,8 visite in Belgio, 1,4 in Germania e 2,1 in Olanda;<\/li>\n<\/ul>\n<h2>considerato che<\/h2>\n<ul>\n<li>il ruolo molto limitato dell\u2019Odontoiatria nell\u2019ambito del SSN crea, pertanto, un evidente ostacolo alla concreta applicazione del principio della globalit\u00e0 delle garanzie offerte dal SSN producendo disuguaglianze nell\u2019accesso all\u2019assistenza odontoiatrica in relazione al reddito, considerati gli alti costi delle prestazioni offerte in regime privato e la scarsit\u00e0 di prestazioni odontoiatriche previste tra i benefici di assicurazioni volontarie;<\/li>\n<li>a tali squilibri intende dare risposta l\u2019odontoiatria sociale, ovvero cure odontoiatriche di qualit\u00e0, che adottano procedure sicure (congrua sterilizzazione, utilizzo di materiali certificati ISO) a prezzi accessibili;<\/li>\n<\/ul>\n<h2>rilevato che<\/h2>\n<ul>\n<li>la normativa nazionale in materia erogazione delle prestazioni odontoiatriche \u00e8 costituita principalmente dal decreto legislativo 30 dicembre 1992, n. 502 (<em>Riordino della disciplina in materia sanitaria<\/em>) che definisce i criteri per la determinazione dei LEA e disciplina il funzionamento dei Fondi integrativi del SSN, nonch\u00e9 dal Decreto del Presidente del Consiglio dei Ministri 29 novembre 2001 di definizione degli attuali Livelli (di cui \u00e8 imminente il superamento);<\/li>\n<li>tali norme prevedono che l\u2019assistenza odontoiatrica a carico del SSN sia limitata a soli due ambiti: programmi di tutela della salute odontoiatrica in et\u00e0 evolutiva e assistenza odontoiatrica e protesica a determinate categorie di soggetti in condizioni di particolare vulnerabilit\u00e0. Tali categorie vengono concretamente individuate nei cittadini appartenenti, nel caso dell\u2019et\u00e0 evolutiva, alla fascia di et\u00e0 da zero a 14 anni che richiedano il monitoraggio e trattamento di carie e malocclusioni e la correzione delle patologie otorinolaringoiatriche a maggiore rischio;<\/li>\n<li>nel caso della particolare vulnerabilit\u00e0 sono, invece, individuati quali beneficiari i cittadini in condizione di svantaggio sociale ed economico correlate al basso reddito, a condizioni di marginalit\u00e0 e\/o esclusione sociale che impediscono l\u2019accesso alle cure odontoiatriche a pagamento (vulnerabilit\u00e0 sociale) e condizioni di tipo sanitario \u2013 quali labiopalatoschisi, stati di immunodeficienza, etc. \u2013 che rendono necessarie le cure odontoiatriche;<\/li>\n<\/ul>\n<h2>ritenuto che<\/h2>\n<ul>\n<li>debbano essere comunque garantite le prestazioni di visita odontoiatrica e di trattamento immediato delle urgenze odontostomatologiche a tutti i cittadini, inclusi quelli che non rientrano nelle categorie di protezione sopra indicate;<\/li>\n<\/ul>\n<h2>ricordato che<\/h2>\n<ul>\n<li>nella nostra regione sono stati gi\u00e0 avviati nel corso degli anni numerosi progetti volti a consentire l\u2019accesso alle cure odontoiatriche a prezzi accessibili ad un maggior numero di persone. Il progetto pi\u00f9 recente, avviato a gennaio 2016, riguarda la Dental School dell\u2019AOU Citt\u00e0 della Salute e della Scienza di Torino che fornisce prestazioni, a prezzi destinati a coprire le sole spese di esercizio, anche ai cittadini che non rientrano nelle categorie degli aventi diritto in base ai LEA. Analogo progetto sperimentale era stato realizzato nel 2013 dall\u2019ASL TO4, sempre per venire incontro alle esigenze dei cittadini che, per ragioni economiche, non possano usufruire dell\u2019assistenza odontoiatrica di tipo privato;<\/li>\n<li>altre regioni limitrofe come la Lombardia hanno avviato negli ultimi anni iniziative a sostegno dell\u2019odontoiatria sociale, in particolare con la deliberazione n. X\/1364 del 14 febbraio 2014 avente ad <em>oggetto \u201cApprovazione del progetto sperimentale di ricerca \u201cvalutazione comparativa di modelli gestionali per l\u2019erogazione delle prestazioni di odontoiatria sociale di qualit\u00e0 nell\u2019et\u00e0 geriatria\u201d<\/em>, con l\u2019intento di garantire prestazioni odontoiatriche relative a protesi dentarie per le fasce pi\u00f9 deboli della popolazione in base a criteri basati sul reddito e l\u2019et\u00e0;<\/li>\n<\/ul>\n<h2>sottolineato che<\/h2>\n<ul>\n<li>dati gli attuali criteri estremamente restrittivi che regolano l\u2019accesso alle cure odontoiatriche nell\u2019ambito del SSN, gli ambulatori odontoiatrici pubblici vengono sottoutilizzati;<\/li>\n<\/ul>\n<h3>IMPEGNA\u00a0<strong>la Giunta regionale del Piemonte<\/strong><\/h3>\n<ul>\n<li>a elaborare modelli gestionali per l\u2019erogazione di prestazioni odontoiatriche accessibili ad una pi\u00f9 ampia fascia di popolazione, in modo da rispondere ad un bisogno di salute diffuso, ma attualmente inevaso da parte del settore pubblico e lasciato al mercato;<\/li>\n<li>a prevedere l\u2019uso <em>full time<\/em> degli ambulatori odontoiatrici pubblici aprendo al settore privato, introducendo opportune modalit\u00e0 controllo delle tariffe e della qualit\u00e0 delle prestazioni da parte della Regione.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Ordine del giorno di Paolo Allemano: Linee guida per l\u2019erogazione di prestazioni odontoiatriche in regime di extra LEA nell\u2019ambito del Servizio sanitario pubblico Il Consiglio regionale del Piemonte,\u00a0premesso che il ruolo dell\u2019Odontoiatria all\u2019interno del Sistema Sanitario Nazionale (SSN) \u00e8 al centro di una annosa controversa. Infatti l\u2019Odontoiatria fatica a trovare una corretta collocazione nell\u2019ambito della [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":1306,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[37],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.12 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Linee guida per l\u2019erogazione di prestazioni odontoiatriche nell\u2019ambito del Servizio sanitario pubblico - Partito Democratico<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"\/web\/2016\/03\/31\/1305\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Linee guida per l\u2019erogazione di prestazioni odontoiatriche nell\u2019ambito del Servizio sanitario pubblico - Partito Democratico\" \/>\n<meta property=\"og:description\" content=\"Ordine del giorno di Paolo Allemano: Linee guida per l\u2019erogazione di prestazioni odontoiatriche in regime di extra LEA nell\u2019ambito del Servizio sanitario pubblico Il Consiglio regionale del Piemonte,\u00a0premesso che il ruolo dell\u2019Odontoiatria all\u2019interno del Sistema Sanitario Nazionale (SSN) \u00e8 al centro di una annosa controversa. Infatti l\u2019Odontoiatria fatica a trovare una corretta collocazione nell\u2019ambito della [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"\/web\/2016\/03\/31\/1305\/\" \/>\n<meta property=\"og:site_name\" content=\"Partito Democratico\" \/>\n<meta property=\"article:published_time\" content=\"2016-03-31T09:53:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-03-31T09:53:48+00:00\" \/>\n<meta property=\"og:image\" content=\"\/web\/wp-content\/uploads\/sites\/8\/2016\/03\/Dentista-responsabile_civile.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mastrodicasa\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"mastrodicasa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"\/web\/2016\/03\/31\/1305\/\",\"url\":\"\/web\/2016\/03\/31\/1305\/\",\"name\":\"Linee guida per l\u2019erogazione di prestazioni odontoiatriche nell\u2019ambito del Servizio sanitario pubblico - Partito Democratico\",\"isPartOf\":{\"@id\":\"\/web\/#website\"},\"datePublished\":\"2016-03-31T09:53:02+00:00\",\"dateModified\":\"2016-03-31T09:53:48+00:00\",\"author\":{\"@id\":\"\/web\/#\/schema\/person\/e3213afc750e7648b3ad0561ab389690\"},\"breadcrumb\":{\"@id\":\"\/web\/2016\/03\/31\/1305\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"\/web\/2016\/03\/31\/1305\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"\/web\/2016\/03\/31\/1305\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Linee guida per l\u2019erogazione di prestazioni odontoiatriche nell\u2019ambito del Servizio sanitario pubblico\"}]},{\"@type\":\"WebSite\",\"@id\":\"\/web\/#website\",\"url\":\"\/web\/\",\"name\":\"Partito Democratico\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"\/web\/#\/schema\/person\/e3213afc750e7648b3ad0561ab389690\",\"name\":\"mastrodicasa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"\/web\/#\/schema\/person\/image\/\",\"url\":\"http:\/\/0.gravatar.com\/avatar\/3193e7cdcf94bcc77fa1c5b0cf49f5f6?s=96&d=mm&r=g\",\"contentUrl\":\"http:\/\/0.gravatar.com\/avatar\/3193e7cdcf94bcc77fa1c5b0cf49f5f6?s=96&d=mm&r=g\",\"caption\":\"mastrodicasa\"},\"url\":\"\/web\/author\/mastrodicasa\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Linee guida per l\u2019erogazione di prestazioni odontoiatriche nell\u2019ambito del Servizio sanitario pubblico - Partito Democratico","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"\/web\/2016\/03\/31\/1305\/","og_locale":"it_IT","og_type":"article","og_title":"Linee guida per l\u2019erogazione di prestazioni odontoiatriche nell\u2019ambito del Servizio sanitario pubblico - Partito Democratico","og_description":"Ordine del giorno di Paolo Allemano: Linee guida per l\u2019erogazione di prestazioni odontoiatriche in regime di extra LEA nell\u2019ambito del Servizio sanitario pubblico Il Consiglio regionale del Piemonte,\u00a0premesso che il ruolo dell\u2019Odontoiatria all\u2019interno del Sistema Sanitario Nazionale (SSN) \u00e8 al centro di una annosa controversa. Infatti l\u2019Odontoiatria fatica a trovare una corretta collocazione nell\u2019ambito della [&hellip;]","og_url":"\/web\/2016\/03\/31\/1305\/","og_site_name":"Partito Democratico","article_published_time":"2016-03-31T09:53:02+00:00","article_modified_time":"2016-03-31T09:53:48+00:00","og_image":[{"width":1920,"height":1280,"url":"\/web\/wp-content\/uploads\/sites\/8\/2016\/03\/Dentista-responsabile_civile.jpg","type":"image\/jpeg"}],"author":"mastrodicasa","twitter_misc":{"Scritto da":"mastrodicasa","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"\/web\/2016\/03\/31\/1305\/","url":"\/web\/2016\/03\/31\/1305\/","name":"Linee guida per l\u2019erogazione di prestazioni odontoiatriche nell\u2019ambito del Servizio sanitario pubblico - Partito Democratico","isPartOf":{"@id":"\/web\/#website"},"datePublished":"2016-03-31T09:53:02+00:00","dateModified":"2016-03-31T09:53:48+00:00","author":{"@id":"\/web\/#\/schema\/person\/e3213afc750e7648b3ad0561ab389690"},"breadcrumb":{"@id":"\/web\/2016\/03\/31\/1305\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["\/web\/2016\/03\/31\/1305\/"]}]},{"@type":"BreadcrumbList","@id":"\/web\/2016\/03\/31\/1305\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"\/web\/"},{"@type":"ListItem","position":2,"name":"Linee guida per l\u2019erogazione di prestazioni odontoiatriche nell\u2019ambito del Servizio sanitario pubblico"}]},{"@type":"WebSite","@id":"\/web\/#website","url":"\/web\/","name":"Partito Democratico","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"\/web\/#\/schema\/person\/e3213afc750e7648b3ad0561ab389690","name":"mastrodicasa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"\/web\/#\/schema\/person\/image\/","url":"http:\/\/0.gravatar.com\/avatar\/3193e7cdcf94bcc77fa1c5b0cf49f5f6?s=96&d=mm&r=g","contentUrl":"http:\/\/0.gravatar.com\/avatar\/3193e7cdcf94bcc77fa1c5b0cf49f5f6?s=96&d=mm&r=g","caption":"mastrodicasa"},"url":"\/web\/author\/mastrodicasa\/"}]}},"_links":{"self":[{"href":"\/web\/wp-json\/wp\/v2\/posts\/1305"}],"collection":[{"href":"\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"\/web\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"\/web\/wp-json\/wp\/v2\/comments?post=1305"}],"version-history":[{"count":2,"href":"\/web\/wp-json\/wp\/v2\/posts\/1305\/revisions"}],"predecessor-version":[{"id":1308,"href":"\/web\/wp-json\/wp\/v2\/posts\/1305\/revisions\/1308"}],"wp:featuredmedia":[{"embeddable":true,"href":"\/web\/wp-json\/wp\/v2\/media\/1306"}],"wp:attachment":[{"href":"\/web\/wp-json\/wp\/v2\/media?parent=1305"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"\/web\/wp-json\/wp\/v2\/categories?post=1305"},{"taxonomy":"post_tag","embeddable":true,"href":"\/web\/wp-json\/wp\/v2\/tags?post=1305"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}