{"id":1288,"date":"2016-03-31T09:38:29","date_gmt":"2016-03-31T07:38:29","guid":{"rendered":"\/web\/?p=1288"},"modified":"2016-03-31T09:59:18","modified_gmt":"2016-03-31T07:59:18","slug":"finanziare-gli-interventi-di-prevenzione-del-dissesto-idrogeologico","status":"publish","type":"post","link":"\/web\/2016\/03\/31\/finanziare-gli-interventi-di-prevenzione-del-dissesto-idrogeologico\/","title":{"rendered":"Finanziare gli interventi di prevenzione del dissesto idrogeologico"},"content":{"rendered":"<p><strong>Odg di Walter Ottria: Individuare, nell\u2019ambito della nuova programmazione dei fondi PAR FSC, risorse specifiche finalizzate a finanziare gli interventi di prevenzione del dissesto idrogeologico.<\/strong><\/p>\n<p><strong><em>\u00a0<\/em><\/strong><strong>Il Consiglio regionale del Piemonte,\u00a0<\/strong><strong>premesso che<\/strong><\/p>\n<ul>\n<li>si definisce \u201c<em>dissesto idrogeologico<\/em>\u201d quel processo articolato che va dall\u2019erosione contenuta e lenta alle forme pi\u00f9 consistenti della degradazione superficiale e sotterranea dei versanti, fino alle forme imponenti e gravi delle frane, comprendendo anche fenomeni come alluvioni e valanghe;<\/li>\n<li>in base ai dati del Rapporto Ispra 2015, sono 7145 (l\u201988,3% del totale) i comuni italiani che si trovano in aree ad elevato rischio idrogeologico, occupando circa il 15,8% della superficie complessiva della penisola. In Italia, pi\u00f9 di 7 milioni di persone vivono in zone di potenziale pericolo;<\/li>\n<li>il Piemonte \u00e8 una delle regioni maggiormente caratterizzate da un delicato equilibrio idrogeologico: circa il 12,7% della popolazione piemontese risiede in zone ad elevato rischio, che rappresentano il 12,2% della superficie totale (si pensi che la provincia di Torino \u00e8 seconda solo a Napoli per popolazione residente in aree ad alto rischio);<\/li>\n<li>secondo dati di ARPA Piemonte, i settori del territorio piemontese caratterizzati dalla maggiore frequenza degli eventi di dissesto idrogeologico sono quelli del Verbano-Cusio-Ossola, Biellese e Vercellese, corrispondenti ai bacini del Toce, Sesia e Cervo, la provincia di Alessandria in corrispondenza del bacino del Basso Tanaro e l\u2019area metropolitana del torinese;<\/li>\n<\/ul>\n<p><strong>considerato che<\/strong><\/p>\n<ul>\n<li>in Piemonte sono stati stanziati negli anni importanti risorse per far fronte alle esigenze conseguenti alle emergenze e ai danni determinati dagli eventi alluvionali alle abitazioni, alla viabilit\u00e0, al sistema idrico e alle attivit\u00e0 economiche, industriali e manifatturiere per prime, insieme al tessuto delle piccole e medie imprese. Secondo dati ricavati dal progetto Risknat seguito dal Settore Prevenzione territoriale del rischio geologico, dall\u2019evento del maggio 1977 all\u2019alluvione dell\u2019ottobre-novembre 2014, le spese per il ripristino sono ammontate ad oltre 2 miliardi di euro;<\/li>\n<li>tuttavia, gli interventi necessari per la messa in sicurezza del nostro territorio e per un\u2019efficace azione di prevenzione richiederebbero risorse aggiuntive considerevoli. Pi\u00f9 precisamente, secondo quanto emerso nel corso dei lavori degli Stati Generali sul dissesto idrogeologico in Piemonte dello scorso 22 aprile, dovrebbero essere effettuati sul territorio regionale ancora circa 500 interventi per oltre 1,24 miliardi di euro,<\/li>\n<\/ul>\n<p><strong>ricordato che <\/strong><\/p>\n<ul>\n<li>l\u2019articolo 61 della Legge Finanziaria 2003 ha istituito il Fondo di Sviluppo e Coesione (FSC), modificato poi con la Legge Finanziaria 2003. Tale Fondo \u00e8 utilizzato, attraverso il Programma attuativo regionale (PAR FSC), per finalit\u00e0 di riequilibrio economico e sociale, nonch\u00e9 per investimenti pubblici e incentivi, dando in tal modo attuazione al comma 5 dell\u2019articolo 119 della Costituzione;<\/li>\n<li>nel Documento Unitario di Programmazione (DUP), principale riferimento programmatico del PAR FSC, strutturato in Assi e Linee Regionali di Intervento, tra le priorit\u00e0 relative alla sostenibilit\u00e0 ambientale sono indicate chiaramente la prevenzione dei rischi e la difesa del suolo e dell\u2019assetto idrogeologico;<strong>\u00a0<\/strong><\/li>\n<\/ul>\n<p><strong>sottolineato che <\/strong><\/p>\n<ul>\n<li>per tale ragione, un\u2019importante riferimento, per quanto concerne le risorse da destinare agli interventi di prevenzione del dissesto idrogeologico, \u00e8 costituito proprio dai fondi basati sul PAR FSC;<\/li>\n<\/ul>\n<p><strong>IMPEGNA\u00a0<\/strong><strong>la Giunta regionale<\/strong><\/p>\n<ul>\n<li>a individuare, nell\u2019ambito della nuova programmazione dei fondi PAR FSC, risorse finalizzate a finanziare gli interventi di prevenzione del dissesto idrogeologico sul territorio regionale.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Odg di Walter Ottria: Individuare, nell\u2019ambito della nuova programmazione dei fondi PAR FSC, risorse specifiche finalizzate a finanziare gli interventi di prevenzione del dissesto idrogeologico. \u00a0Il Consiglio regionale del Piemonte,\u00a0premesso che si definisce \u201cdissesto idrogeologico\u201d quel processo articolato che va dall\u2019erosione contenuta e lenta alle forme pi\u00f9 consistenti della degradazione superficiale e sotterranea dei versanti, [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":1289,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[57],"tags":[14],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.12 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Finanziare gli interventi di prevenzione del dissesto idrogeologico - Partito Democratico<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"\/web\/2016\/03\/31\/finanziare-gli-interventi-di-prevenzione-del-dissesto-idrogeologico\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Finanziare gli interventi di prevenzione del dissesto idrogeologico - Partito Democratico\" \/>\n<meta property=\"og:description\" content=\"Odg di Walter Ottria: Individuare, nell\u2019ambito della nuova programmazione dei fondi PAR FSC, risorse specifiche finalizzate a finanziare gli interventi di prevenzione del dissesto idrogeologico. \u00a0Il Consiglio regionale del Piemonte,\u00a0premesso che si definisce \u201cdissesto idrogeologico\u201d quel processo articolato che va dall\u2019erosione contenuta e lenta alle forme pi\u00f9 consistenti della degradazione superficiale e sotterranea dei versanti, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"\/web\/2016\/03\/31\/finanziare-gli-interventi-di-prevenzione-del-dissesto-idrogeologico\/\" \/>\n<meta property=\"og:site_name\" content=\"Partito Democratico\" \/>\n<meta property=\"article:published_time\" content=\"2016-03-31T07:38:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-03-31T07:59:18+00:00\" \/>\n<meta property=\"og:image\" content=\"\/web\/wp-content\/uploads\/sites\/8\/2016\/03\/dissesto_idrogeologico9.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mastrodicasa\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"mastrodicasa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"\/web\/2016\/03\/31\/finanziare-gli-interventi-di-prevenzione-del-dissesto-idrogeologico\/\",\"url\":\"\/web\/2016\/03\/31\/finanziare-gli-interventi-di-prevenzione-del-dissesto-idrogeologico\/\",\"name\":\"Finanziare gli interventi di prevenzione del dissesto idrogeologico - Partito Democratico\",\"isPartOf\":{\"@id\":\"\/web\/#website\"},\"datePublished\":\"2016-03-31T07:38:29+00:00\",\"dateModified\":\"2016-03-31T07:59:18+00:00\",\"author\":{\"@id\":\"\/web\/#\/schema\/person\/e3213afc750e7648b3ad0561ab389690\"},\"breadcrumb\":{\"@id\":\"\/web\/2016\/03\/31\/finanziare-gli-interventi-di-prevenzione-del-dissesto-idrogeologico\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"\/web\/2016\/03\/31\/finanziare-gli-interventi-di-prevenzione-del-dissesto-idrogeologico\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"\/web\/2016\/03\/31\/finanziare-gli-interventi-di-prevenzione-del-dissesto-idrogeologico\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Finanziare gli interventi di prevenzione del dissesto idrogeologico\"}]},{\"@type\":\"WebSite\",\"@id\":\"\/web\/#website\",\"url\":\"\/web\/\",\"name\":\"Partito Democratico\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"\/web\/#\/schema\/person\/e3213afc750e7648b3ad0561ab389690\",\"name\":\"mastrodicasa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"\/web\/#\/schema\/person\/image\/\",\"url\":\"http:\/\/0.gravatar.com\/avatar\/3193e7cdcf94bcc77fa1c5b0cf49f5f6?s=96&d=mm&r=g\",\"contentUrl\":\"http:\/\/0.gravatar.com\/avatar\/3193e7cdcf94bcc77fa1c5b0cf49f5f6?s=96&d=mm&r=g\",\"caption\":\"mastrodicasa\"},\"url\":\"\/web\/author\/mastrodicasa\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Finanziare gli interventi di prevenzione del dissesto idrogeologico - Partito Democratico","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"\/web\/2016\/03\/31\/finanziare-gli-interventi-di-prevenzione-del-dissesto-idrogeologico\/","og_locale":"it_IT","og_type":"article","og_title":"Finanziare gli interventi di prevenzione del dissesto idrogeologico - Partito Democratico","og_description":"Odg di Walter Ottria: Individuare, nell\u2019ambito della nuova programmazione dei fondi PAR FSC, risorse specifiche finalizzate a finanziare gli interventi di prevenzione del dissesto idrogeologico. \u00a0Il Consiglio regionale del Piemonte,\u00a0premesso che si definisce \u201cdissesto idrogeologico\u201d quel processo articolato che va dall\u2019erosione contenuta e lenta alle forme pi\u00f9 consistenti della degradazione superficiale e sotterranea dei versanti, [&hellip;]","og_url":"\/web\/2016\/03\/31\/finanziare-gli-interventi-di-prevenzione-del-dissesto-idrogeologico\/","og_site_name":"Partito Democratico","article_published_time":"2016-03-31T07:38:29+00:00","article_modified_time":"2016-03-31T07:59:18+00:00","og_image":[{"width":1600,"height":1200,"url":"\/web\/wp-content\/uploads\/sites\/8\/2016\/03\/dissesto_idrogeologico9.jpg","type":"image\/jpeg"}],"author":"mastrodicasa","twitter_misc":{"Scritto da":"mastrodicasa","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"\/web\/2016\/03\/31\/finanziare-gli-interventi-di-prevenzione-del-dissesto-idrogeologico\/","url":"\/web\/2016\/03\/31\/finanziare-gli-interventi-di-prevenzione-del-dissesto-idrogeologico\/","name":"Finanziare gli interventi di prevenzione del dissesto idrogeologico - Partito Democratico","isPartOf":{"@id":"\/web\/#website"},"datePublished":"2016-03-31T07:38:29+00:00","dateModified":"2016-03-31T07:59:18+00:00","author":{"@id":"\/web\/#\/schema\/person\/e3213afc750e7648b3ad0561ab389690"},"breadcrumb":{"@id":"\/web\/2016\/03\/31\/finanziare-gli-interventi-di-prevenzione-del-dissesto-idrogeologico\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["\/web\/2016\/03\/31\/finanziare-gli-interventi-di-prevenzione-del-dissesto-idrogeologico\/"]}]},{"@type":"BreadcrumbList","@id":"\/web\/2016\/03\/31\/finanziare-gli-interventi-di-prevenzione-del-dissesto-idrogeologico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"\/web\/"},{"@type":"ListItem","position":2,"name":"Finanziare gli interventi di prevenzione del dissesto idrogeologico"}]},{"@type":"WebSite","@id":"\/web\/#website","url":"\/web\/","name":"Partito Democratico","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"\/web\/#\/schema\/person\/e3213afc750e7648b3ad0561ab389690","name":"mastrodicasa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"\/web\/#\/schema\/person\/image\/","url":"http:\/\/0.gravatar.com\/avatar\/3193e7cdcf94bcc77fa1c5b0cf49f5f6?s=96&d=mm&r=g","contentUrl":"http:\/\/0.gravatar.com\/avatar\/3193e7cdcf94bcc77fa1c5b0cf49f5f6?s=96&d=mm&r=g","caption":"mastrodicasa"},"url":"\/web\/author\/mastrodicasa\/"}]}},"_links":{"self":[{"href":"\/web\/wp-json\/wp\/v2\/posts\/1288"}],"collection":[{"href":"\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"\/web\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"\/web\/wp-json\/wp\/v2\/comments?post=1288"}],"version-history":[{"count":3,"href":"\/web\/wp-json\/wp\/v2\/posts\/1288\/revisions"}],"predecessor-version":[{"id":1292,"href":"\/web\/wp-json\/wp\/v2\/posts\/1288\/revisions\/1292"}],"wp:featuredmedia":[{"embeddable":true,"href":"\/web\/wp-json\/wp\/v2\/media\/1289"}],"wp:attachment":[{"href":"\/web\/wp-json\/wp\/v2\/media?parent=1288"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"\/web\/wp-json\/wp\/v2\/categories?post=1288"},{"taxonomy":"post_tag","embeddable":true,"href":"\/web\/wp-json\/wp\/v2\/tags?post=1288"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}